{"id":132,"date":"2021-05-26T15:56:13","date_gmt":"2021-05-26T13:56:13","guid":{"rendered":"https:\/\/wp-vorlage-elementor.um-server.de\/?page_id=132"},"modified":"2026-04-22T16:22:54","modified_gmt":"2026-04-22T14:22:54","slug":"privacy-statement","status":"publish","type":"page","link":"https:\/\/varify.io\/en\/privacy-statement\/","title":{"rendered":"Privacy policy"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"132\" class=\"elementor elementor-132\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-4a13d94 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4a13d94\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-845e63f\" data-id=\"845e63f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a3e290 elementor-widget elementor-widget-heading\" data-id=\"4a3e290\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Datenschutzerkl\u00e4rung<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a97536 elementor-toc--minimized-on-tablet elementor-widget elementor-widget-table-of-contents\" data-id=\"4a97536\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;headings_by_tags&quot;:[&quot;h1&quot;],&quot;exclude_headings_by_selector&quot;:[],&quot;marker_view&quot;:&quot;bullets&quot;,&quot;icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;no_headings_message&quot;:&quot;No headings were found on this page.&quot;,&quot;minimize_box&quot;:&quot;yes&quot;,&quot;minimized_on&quot;:&quot;tablet&quot;,&quot;hierarchical_view&quot;:&quot;yes&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t\t\t\t<h4 class=\"elementor-toc__header-title\">\n\t\t\t\tInhalt\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--expand\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__4a97536\" aria-expanded=\"true\" aria-label=\"Abrir la tabla de contenidos\"><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/div>\n\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--collapse\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__4a97536\" aria-expanded=\"true\" aria-label=\"Cerrar la tabla de contenidos\"><i aria-hidden=\"true\" class=\"fas fa-chevron-up\"><\/i><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"elementor-toc__4a97536\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<i class=\"elementor-toc__spinner eicon-animation-spin eicon-loading\" aria-hidden=\"true\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4c38c3 elementor-widget-tablet__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"d4c38c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>1. Einleitung<\/h1><p>Im Folgenden informieren wir \u00fcber die Verarbeitung personenbezogener Daten bei der Nutzung<\/p><ul><li>unserer Website https:\/\/varify.io<\/li><li>unserer Profile in Sozialen Medien.<\/li><\/ul><p>Personenbezogene Daten sind alle Daten, die auf eine konkrete nat\u00fcrliche Person beziehbar sind, z. B. ihr Name oder ihre IP-Adresse.<\/p><h2>1.1. Kontaktdaten<\/h2><p>Verantwortlicher gem. Art. 4 Abs. 7 EU-Datenschutz-Grundverordnung (DSGVO) ist Varify GmbH, S\u00fcdliche M\u00fcnchner Stra\u00dfe 55, 82031 Gr\u00fcnwald, Deutschland, E-Mail: info@varify.io. Gesetzlich vertreten werden wir durch Thomas Kraus.<\/p><p>Unser Datenschutzbeauftragter ist Martin Bastius \u00fcber die heyData GmbH, Sch\u00fctzenstra\u00dfe 5, 10117 Berlin, <a href=\"https:\/\/www.heydata.eu\" data-auto-event-observed=\"true\" target=\"_blank\" rel=\"noopener\">www.heydata.eu<\/a>, E-Mail: datenschutz@heydata.eu erreichbar.<\/p><h2>1.2. Umfang der Datenverarbeitung, Verarbeitungszwecke und Rechtsgrundlagen<\/h2><p>Den Umfang der Verarbeitung der Daten, Verarbeitungszwecke und Rechtsgrundlagen f\u00fchren wir im Detail weiter unten aus. Als Rechtsgrundlage f\u00fcr eine Datenverarbeitung kommen grunds\u00e4tzlich die folgenden in Betracht:<\/p><ul><li>6 Abs. 1 S. 1 lit. a DSGVO dient uns als Rechtsgrundlage f\u00fcr Verarbeitungsvorg\u00e4nge, f\u00fcr die wir eine Einwilligung einholen.<\/li><li>6 Abs. 1 S. 1 lit. b DSGVO ist Rechtsgrundlage, soweit die Verarbeitung personenbezogener Daten zur Erf\u00fcllung eines Vertrages erforderlich ist, z.B. wenn ein Seitenbesucher von uns ein Produkt erwirbt oder wir f\u00fcr ihn eine Leistung ausf\u00fchren. Diese Rechtsgrundlage gilt auch f\u00fcr Verarbeitungen, die f\u00fcr vorvertragliche Ma\u00dfnahmen erforderlich sind, etwa bei Anfragen zu unseren Produkten oder Leistungen.<\/li><li>6 Abs. 1 S. 1 lit. c DSGVO findet Anwendung, wenn wir mit der Verarbeitung personenbezogener Daten eine rechtliche Verpflichtung erf\u00fcllen, wie es z.B. im Steuerrecht der Fall sein kann.<\/li><li>6 Abs. 1 S. 1 lit. f DSGVO dient als Rechtsgrundlage, wenn wir uns zur Verarbeitung personenbezogener Daten auf berechtigte Interessen berufen k\u00f6nnen, z.B. f\u00fcr Cookies, die f\u00fcr den technischen Betrieb unserer Website erforderlich sind.<\/li><\/ul><h2>1.3. Datenverarbeitung au\u00dferhalb des EWR<\/h2><p>Soweit wir Daten an Dienstleister oder sonstige Dritte au\u00dferhalb des EWR \u00fcbermitteln, garantieren Angemessenheitsbeschl\u00fcsse der EU-Kommission nach Art. 45 Ab. 3 DSGVO die Sicherheit der Daten bei der Weitergabe, soweit diese vorhanden sind, wie dies z.B. f\u00fcr Gro\u00dfbritannien, Kanada und Israel der Fall ist.<\/p><p>Bei der Datenweitergabe an Dienstleister in den USA, ist Rechtsgrundlage f\u00fcr die Datenweitergabe ein Angemessenheitsbeschluss der EU-Kommission, wenn sich der Dienstleister zus\u00e4tzlich unter dem EU US Data Privacy Framework zertifiziert hat.<\/p><p>In anderen F\u00e4llen (z.B. wenn kein Angemessenheitsbeschluss existiert), sind Rechtsgrundlage f\u00fcr die Datenweitergabe im Regelfall, also soweit wir keinen abweichenden Hinweis geben, Standardvertragsklauseln. Diese sind ein von der EU-Kommission verabschiedetes Regelwerk und Teil des Vertrags mit dem jeweiligen Dritten. Nach Art. 46 Abs. 2 lit. b DSGVO gew\u00e4hrleisten sie die Sicherheit der Datenweitergabe. Viele der Anbieter haben \u00fcber die Standardvertragsklauseln hinausgehende vertragliche Garantien abgegeben, die die Daten \u00fcber die Standardvertragsklauseln hinaus sch\u00fctzen. Das sind z.B. Garantien hinsichtlich der Verschl\u00fcsselung der Daten oder hinsichtlich einer Pflicht des Dritten zum Hinweis an Betroffene, wenn Strafverfolgungsorgane auf Daten zugreifen wollen.<\/p><h2>1.4. Speicherdauer<\/h2><p>Sofern nicht im Rahmen dieser Datenschutzerkl\u00e4rung ausdr\u00fccklich angegeben, werden die bei uns gespeicherten Daten gel\u00f6scht, sobald sie f\u00fcr ihre Zweckbestimmung nicht mehr erforderlich sind und der L\u00f6schung keine gesetzlichen Aufbewahrungspflichten entgegenstehen. Sofern die Daten nicht gel\u00f6scht werden, weil sie f\u00fcr andere und gesetzlich zul\u00e4ssige Zwecke erforderlich sind, wird ihre Verarbeitung eingeschr\u00e4nkt, d.h. die Daten werden gesperrt und nicht f\u00fcr andere Zwecke verarbeitet. Das gilt z.B. f\u00fcr Daten, die wir aus handels- oder steuerrechtlichen Gr\u00fcnden aufbewahren m\u00fcssen.<\/p><h2>1.5. Rechte der Betroffenen<\/h2><p>Betroffene haben gegen\u00fcber uns folgende Rechte hinsichtlich der sie betreffenden personenbezogenen Daten:<\/p><ul><li>Recht auf Auskunft,<\/li><li>Recht auf Berichtigung oder L\u00f6schung,<\/li><li>Recht auf Einschr\u00e4nkung der Verarbeitung,<\/li><li><strong>Recht auf Widerspruch gegen die Verarbeitung<\/strong>,<\/li><li>Recht auf Daten\u00fcbertragbarkeit,<\/li><li><strong>Recht, eine erteilte Einwilligung jederzeit zu widerrufen<\/strong>.<\/li><\/ul><p>Betroffene haben zudem das Recht, sich bei einer Datenschutz-Aufsichtsbeh\u00f6rde \u00fcber die Verarbeitung ihrer personenbezogenen Daten zu beschweren. Kontaktdaten der Datenschutz-Aufsichtsbeh\u00f6rden sind unter https:\/\/www.bfdi.bund.de\/DE\/Service\/Anschriften\/Laender\/Laender-node.html abrufbar.<\/p><h2>1.6. Pflicht zur Bereitstellung von Daten<\/h2><p>Kunden, Interessenten oder Dritte m\u00fcssen uns im Rahmen einer Gesch\u00e4ftsbeziehung oder sonstigen Beziehung nur diejenigen personenbezogenen Daten bereitstellen, die f\u00fcr die Begr\u00fcndung, Durchf\u00fchrung und Beendigung der Gesch\u00e4ftsbeziehung oder f\u00fcr die sonstige Beziehung erforderlich sind oder zu deren Erhebung wir gesetzlich verpflichtet sind. Ohne diese Daten werden wir in der Regel den Abschluss eines Vertrages oder die Bereitstellung einer Leistung ablehnen m\u00fcssen oder einen bestehenden Vertrag oder sonstige Beziehung nicht mehr durchf\u00fchren k\u00f6nnen.<\/p><p>Pflichtangaben sind als solche gekennzeichnet.<\/p><h2>1.7. Keine automatische Entscheidungsfindung im Einzelfall<\/h2><p>Zur Begr\u00fcndung und Durchf\u00fchrung einer Gesch\u00e4ftsbeziehung oder sonstigen Beziehung nutzen wir grunds\u00e4tzlich keine vollautomatisierte Entscheidungsfindung gem\u00e4\u00df Artikel 22 DSGVO. Sollten wir diese Verfahren in Einzelf\u00e4llen einsetzen, werden wir hier\u00fcber gesondert informieren, sofern dies gesetzlich geboten ist.<\/p><h2>1.8. Kontaktaufnahme<\/h2><p>Bei der Kontaktaufnahme mit uns, z.B. per E-Mail oder Telefon, werden die uns mitgeteilten Daten (z.B. Namen und E-Mail-Adressen) von uns gespeichert, um Fragen zu beantworten. Rechtsgrundlage f\u00fcr die Verarbeitung ist unser berechtigtes Interesse (Art. 6 Abs. 1 S. 1 lit. f DSGVO), an uns gerichtete Anfragen zu beantworten. Die in diesem Zusammenhang anfallenden Daten l\u00f6schen wir, nachdem die Speicherung nicht mehr erforderlich ist, oder schr\u00e4nken die Verarbeitung ein, falls gesetzliche Aufbewahrungspflichten bestehen.<\/p><h2>1.9. Kundenumfragen<\/h2><p>Von Zeit zu Zeit f\u00fchren wir Kundenumfragen durch, um unsere Kunden und ihre W\u00fcnsche besser kennenzulernen. Dabei erheben wir die jeweils abgefragten Daten. Es ist unser berechtigtes Interesse, unsere Kunden und ihre W\u00fcnsche besser kennenzulernen, so dass Rechtsgrundlage der damit einhergehenden Datenverarbeitung Art. 6 Abs. 1 S. 1 lit f DSGVO ist. Die Daten l\u00f6schen wir, wenn die Ergebnisse der Umfragen ausgewertet sind.<\/p><h1>2. Newsletter<\/h1><p>Interessenten haben die M\u00f6glichkeit, einen kostenlosen Newsletter zu abonnieren. Wir verarbeiten die bei der Anmeldung angegebenen Daten ausschlie\u00dflich f\u00fcr den Versand des Newsletters. Die Anmeldung erfolgt \u00fcber die Auswahl des entsprechenden Feldes auf unserer Website, durch Ankreuzen des entsprechenden Feldes in einem Papierdokument oder durch eine andere eindeutige Handlung, wodurch Interessenten ihr Einverst\u00e4ndnis in die Verarbeitung ihrer Daten erkl\u00e4ren, so dass Rechtsgrundlage Art. 6 Abs. 1 S. 1 lit. a DSGVO ist. Die Einwilligung kann jederzeit widerrufen werden, z.B. durch Klicken des entsprechenden Links im Newsletter oder Hinweis an unsere oben angegebene E-Mail-Adresse. Die Verarbeitung der Daten bis zum Widerruf bleibt auch im Falle eines Widerrufs rechtm\u00e4\u00dfig.<\/p><p>Auf Grundlage der Einwilligung der Empf\u00e4nger (Art. 6 Abs. 1 S. 1 lit. a DSGVO)\u00a0messen wir auch die \u00d6ffnungs- und Klickrate unserer Newsletter, um zu verstehen, welche Inhalte relevant f\u00fcr unsere Empf\u00e4nger sind.<\/p><p>Wir versenden Newsletter mit dem Tool HubSpot des Anbieters HubSpot, Inc., 25 1st Street Cambridge, MA 0214, USA (Datenschutzerkl\u00e4rung: https:\/\/legal.hubspot.com\/de\/privacy-policy). Der Anbieter verarbeitet dabei Inhalts-, Nutzungs-, Meta-\/Kommunikationsdaten und Kontaktdaten in der EU.<\/p><h1>3. Datenverarbeitung auf unserer Website<\/h1><h2>3.1. Hinweis f\u00fcr Websitebesucher aus Deutschland<\/h2><p>Unsere Website speichert Informationen in der Endeinrichtung von Websitebesuchern (z.B. Cookies) oder greift auf Informationen zu, die bereits in der Endeinrichtung gespeichert sind (z.B. IP-Adressen). Welche Informationen dies im Einzelnen sind, ist den folgenden Abschnitten zu entnehmen.<\/p><p>Diese Speicherung und dieser Zugriff erfolgt auf Grundlage der folgenden Bestimmungen:<\/p><ul><li>Soweit diese Speicherung oder dieser Zugriff unbedingt erforderlich ist, damit wir dem von Websitebesuchern ausdr\u00fccklich gew\u00fcnschten Dienst unserer Website zur Verf\u00fcgung stellen (z.B. zur Durchf\u00fchrung eines vom Websitebesucher genutzten Chatbot oder zur Sicherstellung der IT-Sicherheit unserer Website), erfolgt sie auf Grundlage von \u00a7 25 Abs. 2 Nr. 2 TTDSG.<\/li><li>Im \u00dcbrigen erfolgt diese Speicherung oder dieser Zugriff auf Grundlage der Einwilligung der Websitebesucher (\u00a7 25 Abs. 1 TTDSG).<\/li><\/ul><p>Die nachgelagerte Datenverarbeitung erfolgt nach Ma\u00dfgabe der folgenden Abschnitte und auf Grundlage der Vorschriften der DSGVO.<\/p><h2>3.2. Informatorische Nutzung der Website<\/h2><p>Bei der informatorischen Nutzung der Website, also wenn Seitenbesucher uns nicht gesondert Informationen \u00fcbermitteln, erheben wir die personenbezogenen Daten, die der Browser an unseren Server \u00fcbermittelt, um die Stabilit\u00e4t und Sicherheit unserer Website zu gew\u00e4hrleisten. Darin liegt unser berechtigtes Interesse, so dass Rechtsgrundlage ist Art. 6 Abs. 1 S. 1 lit. f DSGVO ist.<\/p><p>Diese Daten sind:<\/p><ul><li>IP-Adresse<\/li><li>Datum und Uhrzeit der Anfrage<\/li><li>Zeitzonendifferenz zur Greenwich Mean Time (GMT)<\/li><li>Inhalt der Anfrage (konkrete Seite)<\/li><li>Zugriffsstatus\/HTTP-Statuscode<\/li><li>jeweils \u00fcbertragene Datenmenge<\/li><li>Website, von der die Anfrage kommt<\/li><li>Browser<\/li><li>Betriebssystem und dessen Oberfl\u00e4che<\/li><li>Sprache und Version der Browsersoftware.<\/li><\/ul><p>Diese Daten werden au\u00dferdem in Logfiles gespeichert. Sie werden gel\u00f6scht, wenn ihre Speicherung nicht mehr erforderlich ist, sp\u00e4testens nach 14 Tagen.<\/p><h2>3.3. Webhosting und Bereitstellung der Website<\/h2><p>Unsere Website hostet Amazon AWS. Anbieter ist Amazon Web Services EMEA S\u00e0rl, Avenue John F. Kennedy 38, 1855 Luxemburg, Luxemburg. Der Anbieter verarbeitet dabei die \u00fcber die Website \u00fcbermittelten personenbezogenen Daten, z.B. Inhalts-, Nutzungs-, Meta-\/Kommunikationsdaten oder Kontaktdaten, in der EU. Weitere Informationen finden sich in der Datenschutzerkl\u00e4rung des Anbieters unter https:\/\/aws.amazon.com\/privacy\/.<\/p><p>Es ist unser berechtigtes Interesse, eine Website zur Verf\u00fcgung zu stellen, so dass die Rechtsgrundlage der beschriebenen Datenverarbeitung Art. 6 Abs. 1 S. 1 lit. f DSGVO ist.<\/p><p>Wir nutzen das Content Delivery Network Cloudflare f\u00fcr unsere Website. Anbieter ist Cloudflare, Inc., 101 Townsend St., San Francisco, CA 94107, USA. Der Anbieter verarbeitet dabei die \u00fcber die Website \u00fcbermittelten personenbezogenen Daten, z.B. Inhalts-, Nutzungs-, Meta-\/Kommunikations- oder Kontaktdaten in den USA. Weitere Informationen finden Sie in der Datenschutzerkl\u00e4rung des Anbieters unter https:\/\/www.cloudflare.com\/de-de\/privacypolicy\/.<\/p><p>Wir haben ein berechtigtes Interesse daran, ausreichende Speicher- und Auslieferungskapazit\u00e4ten zu nutzen, um auch bei gro\u00dfen Lastspitzen einen optimalen Datendurchsatz zu gew\u00e4hrleisten. Die Rechtsgrundlage der beschriebenen Datenverarbeitung ist daher Art. 6 Abs. 1 S. 1 lit. f GDPR.<\/p><p>Rechtsgrundlage der \u00dcbermittlung in ein Land au\u00dferhalb des EWR sind Angemessenheitsbeschluss. Die Sicherheit der in das Drittland (also einem Land au\u00dferhalb des EWR) \u00fcbermittelten Daten ist gew\u00e4hrleistet, weil die EU-Kommission im Rahmen eines Angemessenheitsbeschluss nach Art. 45 Abs. 3 DSGVO beschlossen hat, dass das Drittland ein angemessenes Schutzniveau bietet.<\/p><h2>3.4. Kontaktformular<\/h2><p>Bei Kontaktaufnahme \u00fcber das Kontaktformular auf unserer Website speichern wir die dort abgefragten Daten und den Inhalt der Nachricht.<br \/>Rechtsgrundlage f\u00fcr die Verarbeitung ist unser berechtigtes Interesse, an uns gerichtete Anfragen zu beantworten. Rechtsgrundlage f\u00fcr die Verarbeitung ist deshalb Art. 6 Abs. 1 S. 1 lit. f DSGVO.<br \/>Die in diesem Zusammenhang anfallenden Daten l\u00f6schen wir, nachdem die Speicherung nicht mehr erforderlich ist, oder schr\u00e4nken die Verarbeitung ein, falls gesetzliche Aufbewahrungspflichten bestehen.<\/p><h2>3.5. Stellenanzeigen<\/h2><p>Wir ver\u00f6ffentlichen Stellen, die in unserem Unternehmen frei sind, auf unserer Website, auf mit der Website verbundenen Seiten oder auf Websites von Dritten.<br \/>Die Verarbeitung der im Rahmen der Bewerbung angegebenen Daten erfolgt zur Durchf\u00fchrung des Bewerbungsverfahrens. Soweit diese f\u00fcr unsere Entscheidung, ein Besch\u00e4ftigungsverh\u00e4ltnis zu begr\u00fcnden, erforderlich sind, ist Rechtsgrundlage Art. 88 Abs. 1 DSGVO i. V. m. \u00a7 26 Abs. 1 BDSG. Die zur Durchf\u00fchrung des Bewerbungsverfahrens erforderlichen Daten haben wir entsprechend gekennzeichnet oder weisen auf sie hin. Wenn Bewerber diese Daten nicht angeben, k\u00f6nnen wir die Bewerbung nicht bearbeiten.<br \/>Weitere Daten sind freiwillig und nicht f\u00fcr eine Bewerbung erforderlich. Falls Bewerber weitere Angaben machen, ist Grundlage ihre Einwilligung (Art. 6 Abs. 1 S. 1 lit. a DSGVO).<\/p><p>Wir bitten Bewerber, in Lebenslauf und Anschreiben auf Angaben zu politischen Meinungen, religi\u00f6sen Anschauungen und \u00e4hnlich sensiblen Daten zu verzichten. Sie sind nicht f\u00fcr eine Bewerbung erforderlich. Wenn Bewerber dennoch entsprechende Angaben machen, k\u00f6nnen wir ihre Verarbeitung im Rahmen der Verarbeitung des Lebenslaufes oder Anschreibens nicht verhindern. Ihre Verarbeitung beruht dann auch auf der Einwilligung der Bewerber (Art. 9 Abs. 2 lit. a DSGVO).<\/p><p>Schlie\u00dflich verarbeiten wir die Daten der Bewerber f\u00fcr weitere Bewerbungsverfahren, wenn sie uns dazu ihre Einwilligung erteilt haben. In diesem Fall ist Rechtsgrundlage Art. 6 Abs. 1 S. 1 lit. a DSGVO.<\/p><p>Die Daten der Bewerber geben wir an die zust\u00e4ndigen Mitarbeiter der Personalabteilung, an unsere Auftragsverarbeiter im Bereich Recruiting und an die im \u00dcbrigen im Bewerbungsverfahren beteiligten Mitarbeiter weiter.<\/p><p>Wenn wir im Anschluss an das Bewerbungsverfahren ein Besch\u00e4ftigungsverh\u00e4ltnis mit dem Bewerber eingehen, l\u00f6schen wir die Daten erst nach Beendigung des Besch\u00e4ftigungsverh\u00e4ltnisses. Andernfalls l\u00f6schen wir die Daten sp\u00e4testens sechs Monate nach Ablehnung eines Bewerbers.<\/p><p>Wenn Bewerber uns ihre Einwilligung erteilt haben, ihre Daten auch f\u00fcr weitere Bewerbungsverfahren zu verwenden, l\u00f6schen wir ihre Daten erst ein Jahr nach Erhalt der Bewerbung.<\/p><h2>3.6. Buchung von Terminen<\/h2><p>Seitenbesucher k\u00f6nnen auf unserer Website Termine mit uns buchen. Daf\u00fcr verarbeiten wir neben den eingegebenen Daten Meta- oder Kommunikationsdaten. Wir haben ein berechtigtes Interesse daran, Interessenten eine nutzerfreundliche M\u00f6glichkeit zur Vereinbarung von Terminen anzubieten. Deshalb ist Rechtsgrundlage der Datenverarbeitung Art. 6 Abs. 1 S. 1 lit. f DSGVO. Soweit wir f\u00fcr die Vereinbarung ein Tool eines Drittanbieters verwenden, sind die Informationen dazu unter &#8222;Drittanbieter&#8220; zu finden.<\/p><h2>3.7. Kundenkonto<\/h2><p>Besucher der Website k\u00f6nnen auf unserer Website ein Kundenkonto er\u00f6ffnen. Wir verarbeiten die in diesem Zusammenhang angeforderten Daten auf der Grundlage des mit dem Nutzer abgeschlossenen Vertrags. Rechtsgrundlage f\u00fcr die Verarbeitung ist deshalb Art. 6 Abs. 1 S. 1 lit. b DSGVO.<\/p><h2>3.8. Angebot von Waren und Dienstleistungen<\/h2><p>Wir bieten \u00fcber unsere Website Waren und Dienstleistungen an. Dabei verarbeiten wir im Rahmen der Bestellung die folgenden Daten:<\/p><p>Firma, Vorname, Nachname, Stra\u00dfe und Hausnummer, PLZ, Stadt, Zahlungsdaten<\/p><p>Die Verarbeitung der Daten erfolgt zur Erbringung des mit dem jeweiligen Seitenbesucher geschlossenen Vertrags (Art. 6 Abs. 1 S. 1 lit. b DSGVO).<\/p><h2>3.9. Zahlungsdienstleister<\/h2><p>Zur Abwicklung von Zahlungen nutzen wir Zahlungsabwickler, die selbst datenschutzrechtlich Verantwortliche im Sinne von Art. 4 Nr. 7 DSGVO sind. Soweit diese von uns im Bestellprozess eingegebene Daten und Zahlungsdaten erhalten, erf\u00fcllen wir damit den mit unseren Kunden geschlossenen Vertrag (Art. 6 Abs. 1 S. 1 lit. b DSGVO).<\/p><p>Diese Zahlungsdienstleister sind:<\/p><ul><li>Stripe Payments Europe, Ltd., Irland<\/li><\/ul><h2>3.10. Technisch notwendige Cookies<\/h2><p>Unsere Website setzt Cookies. Cookies sind kleine Textdateien, die im Webbrowser auf dem Endger\u00e4t eines Seitenbesuchers gespeichert werden. Cookies helfen dabei, das Angebot nutzerfreundlicher, effektiver und sicherer zu machen. Soweit diese Cookies f\u00fcr den Betrieb unserer Website oder ihre Funktionen erforderlich sind (nachfolgend \u201cTechnisch notwendige Cookies\u201d), ist Rechtsgrundlage der damit verbundenen Datenverarbeitung Art. 6 Abs. 1 S. 1 lit. f DSGVO. Wir haben ein berechtigtes Interesse, Kunden und anderen Seitenbesuchern eine funktionsf\u00e4hige Website zur Verf\u00fcgung zu stellen.<br \/>Konkret setzen wir technisch notwendige Cookies zu dem folgenden Zweck oder den folgenden Zwecken:<\/p><ul><li>Cookies that adopt language settings<\/li><li>Local storage objects, which are required for the purpose of A\/B testing in order to be able to display different variants of the website to page visitors<\/li><\/ul><h2>3.11. Drittanbieter<\/h2><h3>3.11.1. Leadinfo<\/h3><p>Wir setzen Leadinfo zur Identifizierung von Gesch\u00e4ftschancen ein. Der Anbieter ist Leadinfo B.V., Rivium Quadrant 141, 2909 LC Capelle aan den IJssel, Niederlande. Der Anbieter verarbeitet Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen) in der EU.<\/p><p>Die Rechtsgrundlage der Verarbeitung ist Art. 6 Abs. 1 S. 1 lit. a DSGVO. Die Verarbeitung erfolgt auf der Basis von Einwilligungen. Betroffene k\u00f6nnen ihre Einwilligung jederzeit widerrufen, indem sie uns z.B. unter den in unserer Datenschutzerkl\u00e4rung angegebenen Kontaktdaten kontaktieren. Der Widerruf ber\u00fchrt nicht die Rechtm\u00e4\u00dfigkeit der Verarbeitung bis zum Widerruf.<\/p><p>Wir l\u00f6schen die Daten, wenn der Zweck ihrer Erhebung entfallen ist. Weitere Informationen sind in der Datenschutzerkl\u00e4rung des Anbieters unter https:\/\/www.leadinfo.com\/de\/datenschutz\/ abrufbar.<\/p><h3>3.11.2. Microsoft Clarity<\/h3><p>Wir setzen Microsoft Clarity zur Identifizierung von Gesch\u00e4ftschancen und zur Analyse ein. Der Anbieter ist Microsoft Ireland Operations, Ltd., One Microsoft Place, South County Business Park, Leopardstown, Dublin 18, D18 P521, Ireland. Der Anbieter verarbeitet Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten) und Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen) in der EU.<\/p><p>Die Rechtsgrundlage der Verarbeitung ist Art. 6 Abs. 1 S. 1 lit. a DSGVO. Die Verarbeitung erfolgt auf der Basis von Einwilligungen. Betroffene k\u00f6nnen ihre Einwilligung jederzeit widerrufen, indem sie uns z.B. unter den in unserer Datenschutzerkl\u00e4rung angegebenen Kontaktdaten kontaktieren. Der Widerruf ber\u00fchrt nicht die Rechtm\u00e4\u00dfigkeit der Verarbeitung bis zum Widerruf.<\/p><p>Die Daten werden gel\u00f6scht, wenn der Zweck ihrer Erhebung entfallen ist und keine Aufbewahrungspflicht entgegensteht. Weitere Informationen sind in der Datenschutzerkl\u00e4rung des Anbieters unter https:\/\/privacy.microsoft.com\/de-de\/privacystatement abrufbar.<\/p><h3>3.11.3. HubSpot LiveChat<\/h3><p>Wir setzen HubSpot LiveChat als Live-Chat ein. Der Anbieter ist HubSpot, Inc., 25 1st Street Cambridge, MA 0214, USA. Der Anbieter verarbeitet Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Inhaltsdaten (z.B. Eingaben in Onlineformularen) und Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen) in der EU.<\/p><p>Die Rechtsgrundlage der Verarbeitung ist Art. 6 Abs. 1 S. 1 lit. a DSGVO. Die Verarbeitung erfolgt auf der Basis von Einwilligungen. Betroffene k\u00f6nnen ihre Einwilligung jederzeit widerrufen, indem sie uns z.B. unter den in unserer Datenschutzerkl\u00e4rung angegebenen Kontaktdaten kontaktieren. Der Widerruf ber\u00fchrt nicht die Rechtm\u00e4\u00dfigkeit der Verarbeitung bis zum Widerruf.<\/p><p>Die Daten werden gel\u00f6scht, wenn der Zweck ihrer Erhebung entfallen ist und keine Aufbewahrungspflichten entgegenstehen. Weitere Informationen sind in der Datenschutzerkl\u00e4rung des Anbieters unter https:\/\/legal.hubspot.com\/de\/privacy-policy abrufbar.<\/p><h3>3.11.4. Google Conversion Tag<\/h3><p>Wir setzen Google Conversion Tag zum Konvertierungs-Tracking ein. Der Anbieter ist Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irland. Der Anbieter verarbeitet Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten) in den USA.<\/p><p>Die Rechtsgrundlage der Verarbeitung ist Art. 6 Abs. 1 S. 1 lit. a DSGVO. Die Verarbeitung erfolgt auf der Basis von Einwilligungen. Betroffene k\u00f6nnen ihre Einwilligung jederzeit widerrufen, indem sie uns z.B. unter den in unserer Datenschutzerkl\u00e4rung angegebenen Kontaktdaten kontaktieren. Der Widerruf ber\u00fchrt nicht die Rechtm\u00e4\u00dfigkeit der Verarbeitung bis zum Widerruf.<\/p><p>Rechtsgrundlage der \u00dcbermittlung in ein Land au\u00dferhalb des EWR sind Standardvertragsklauseln. Die Sicherheit der in das Drittland (also einem Land au\u00dferhalb des EWR) \u00fcbermittelten Daten ist durch gem\u00e4\u00df dem Pr\u00fcfverfahren nach Art. 93 Abs. 2 DSGVO erlassene Standarddatenschutzklauseln gew\u00e4hrleistet (Art. 46 Abs. 2 lit. c DSGVO), die wir mit dem Anbieter vereinbart haben.<\/p><p>Die Daten werden gel\u00f6scht, wenn der Zweck ihrer Erhebung entfallen ist und keine Aufbewahrungspflicht entgegensteht. Weitere Informationen sind in der Datenschutzerkl\u00e4rung des Anbieters unter https:\/\/policies.google.com\/privacy?hl=de https:\/\/support.google.com\/tagmanager\/answer\/9323295?hl=de&amp;ref_topic=3441532 abrufbar.<\/p><h3>3.11.5. Google Analytics<\/h3><p>Wir setzen Google Analytics zur Analyse ein. Der Anbieter ist Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Dublin, Irland. Der Anbieter verarbeitet Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten) und Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen) in den USA.<\/p><p>Die Rechtsgrundlage der Verarbeitung ist Art. 6 Abs. 1 S. 1 lit. a DSGVO. Die Verarbeitung erfolgt auf der Basis von Einwilligungen. Betroffene k\u00f6nnen ihre Einwilligung jederzeit widerrufen, indem sie uns z.B. unter den in unserer Datenschutzerkl\u00e4rung angegebenen Kontaktdaten kontaktieren. Der Widerruf ber\u00fchrt nicht die Rechtm\u00e4\u00dfigkeit der Verarbeitung bis zum Widerruf.<\/p><p>Rechtsgrundlage der \u00dcbermittlung in ein Land au\u00dferhalb des EWR sind Angemessenheitsbeschluss. Die Sicherheit der in das Drittland (also einem Land au\u00dferhalb des EWR) \u00fcbermittelten Daten ist gew\u00e4hrleistet, weil die EU-Kommission im Rahmen eines Angemessenheitsbeschluss nach Art. 45 Abs. 3 DSGVO beschlossen hat, dass das Drittland ein angemessenes Schutzniveau bietet.<\/p><p>Die Daten werden gel\u00f6scht, wenn der Zweck ihrer Erhebung entfallen ist und keine Aufbewahrungspflicht entgegensteht. Weitere Informationen sind in der Datenschutzerkl\u00e4rung des Anbieters unter https:\/\/policies.google.com\/privacy?hl=de abrufbar.<\/p><h3>3.11.6. Google Maps<\/h3><p>Wir setzen Google Maps f\u00fcr Karten auf unserer Website ein. Der Anbieter ist Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Dublin, Irland. Der Anbieter verarbeitet Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten) und Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen) in den USA.<\/p><p>Die Rechtsgrundlage der Verarbeitung ist Art. 6 Abs. 1 S. 1 lit. a DSGVO. Die Verarbeitung erfolgt auf der Basis von Einwilligungen. Betroffene k\u00f6nnen ihre Einwilligung jederzeit widerrufen, indem sie uns z.B. unter den in unserer Datenschutzerkl\u00e4rung angegebenen Kontaktdaten kontaktieren. Der Widerruf ber\u00fchrt nicht die Rechtm\u00e4\u00dfigkeit der Verarbeitung bis zum Widerruf.<\/p><p>Rechtsgrundlage der \u00dcbermittlung in ein Land au\u00dferhalb des EWR sind Einwilligungen.<\/p><p>Wir l\u00f6schen die Daten, wenn der Zweck ihrer Erhebung entfallen ist. Weitere Informationen sind in der Datenschutzerkl\u00e4rung des Anbieters unter https:\/\/policies.google.com\/privacy?hl=de abrufbar.<\/p><h3>3.11.7. YouTube Videos<\/h3><p>Wir setzen YouTube Videos f\u00fcr Videos auf der Website ein. Der Anbieter ist Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irland. Der Anbieter verarbeitet Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten) und Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen) in den USA.<\/p><p>Die Rechtsgrundlage der Verarbeitung ist Art. 6 Abs. 1 S. 1 lit. a DSGVO. Die Verarbeitung erfolgt auf der Basis von Einwilligungen. Betroffene k\u00f6nnen ihre Einwilligung jederzeit widerrufen, indem sie uns z.B. unter den in unserer Datenschutzerkl\u00e4rung angegebenen Kontaktdaten kontaktieren. Der Widerruf ber\u00fchrt nicht die Rechtm\u00e4\u00dfigkeit der Verarbeitung bis zum Widerruf.<\/p><p>Rechtsgrundlage der \u00dcbermittlung in ein Land au\u00dferhalb des EWR sind Einwilligungen.<\/p><p>Weitere Informationen sind in der Datenschutzerkl\u00e4rung des Anbieters unter https:\/\/policies.google.com\/privacy abrufbar.<\/p><h3>3.11.8. Google Tag Manager<\/h3><p>Wir setzen Google Tag Manager zur Ausspielung weiterer Tools ein. Der Anbieter ist Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irland. Der Anbieter verarbeitet Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen) in den USA.<\/p><p>Die Rechtsgrundlage der Verarbeitung ist Art. 6 Abs. 1 S. 1 lit. a DSGVO. Die Verarbeitung erfolgt auf der Basis von Einwilligungen. Betroffene k\u00f6nnen ihre Einwilligung jederzeit widerrufen, indem sie uns z.B. unter den in unserer Datenschutzerkl\u00e4rung angegebenen Kontaktdaten kontaktieren. Der Widerruf ber\u00fchrt nicht die Rechtm\u00e4\u00dfigkeit der Verarbeitung bis zum Widerruf.<\/p><p>Rechtsgrundlage der \u00dcbermittlung in ein Land au\u00dferhalb des EWR sind Angemessenheitsbeschluss. Die Sicherheit der in das Drittland (also einem Land au\u00dferhalb des EWR) \u00fcbermittelten Daten ist gew\u00e4hrleistet, weil die EU-Kommission im Rahmen eines Angemessenheitsbeschluss nach Art. 45 Abs. 3 DSGVO beschlossen hat, dass das Drittland ein angemessenes Schutzniveau bietet.<\/p><p>Wir l\u00f6schen die Daten, wenn der Zweck ihrer Erhebung entfallen ist. Weitere Informationen sind in der Datenschutzerkl\u00e4rung des Anbieters unter https:\/\/policies.google.com\/privacy?hl=de abrufbar.<\/p><h3>3.11.9. heyData<\/h3><p>Wir haben ein Datenschutz-Siegel auf unserer Website eingebunden. Der Anbieter ist heyData GmbH, Sch\u00fctzenstra\u00dfe 5, 10117 Berlin, Deutschland. Der Anbieter verarbeitet Meta-\/Kommunikationsdaten (z.B. IP-Adressen) in der EU.<\/p><p>Die Rechtsgrundlage der Verarbeitung ist Art. 6 Abs. 1 S. 1 lit. f DSGVO. Wir haben ein berechtigtes Interesse, Website-Besuchern eine Best\u00e4tigung \u00fcber unsere Datenschutz-Compliance zur Verf\u00fcgung zu stellen. Gleichzeitig hat der Anbieter ein berechtigtes Interesse daran, sicherzustellen, dass nur Kunden mit bestehenden Vertr\u00e4gen seine Siegel nutzen, weshalb eine blo\u00dfe Bildkopie des Zertifikats keine gangbare Alternative zur Best\u00e4tigung darstellt.<\/p><p>Die Daten werden nach der Erhebung maskiert, damit kein Personenbezug mehr besteht. Weitere Informationen sind in der Datenschutzerkl\u00e4rung des Anbieters unter https:\/\/heydata.eu\/datenschutzerklaerung abrufbar.<\/p><h3>3.11.10. Cookiebot<\/h3><p>Wir setzen Cookiebot zum Management von Einwilligungen ein. Der Anbieter ist Usercentrics A\/S, Havnegade 39, DK-1058, Kopenhagen. Der Anbieter verarbeitet Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen) in der EU.<\/p><p>Die Rechtsgrundlage der Verarbeitung ist Art. 6 Abs. 1 S. 1 lit. f DSGVO. Wir haben ein berechtigtes Interesse daran, die Einwilligungen der Websitebesucher zu Cookies auf einfache Weise zu verwalten.<\/p><p>Die Daten werden gel\u00f6scht, wenn der Zweck ihrer Erhebung entfallen ist und keine Aufbewahrungspflicht entgegensteht. Weitere Informationen sind in der Datenschutzerkl\u00e4rung des Anbieters unter https:\/\/www.cookiebot.com\/de\/privacy-policy\/ abrufbar.<\/p><h3>3.11.11. Varify.io<\/h3><p>Wir setzen varify.io zum A\/B-Testing ein. Der Anbieter ist Varify GmbH, S\u00fcdliche M\u00fcnchner Stra\u00dfe 55, 82031 Gr\u00fcnwald, Deutschland. Der Anbieter verarbeitet Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen) in der EU.<\/p><p>Die Rechtsgrundlage der Verarbeitung ist unser berechtigtes Interesse gem. Art. 6 Abs. 1 S. 1 lit. f DSGVO. Die Verarbeitung der Daten ist technisch notwendig, um Website-Besuchern verschiedene Varianten der Website anzeigen zu lassen.<\/p><p>Wir l\u00f6schen die Daten, wenn der Zweck ihrer Erhebung entfallen ist.<\/p><h3>3.11.12. Mailgun<\/h3><p>Wir setzen Mailgun zur \u00dcbersendung transaktionaler E-Mails ein. Der Anbieter ist Mailgun Technologies, Inc., 112 E Pecan St Ste 1135, San Antonio, TX, 78205-1509, USA. Der Anbieter verarbeitet E-Mail-Adressen in den USA.<\/p><p>Die Rechtsgrundlage der Verarbeitung ist Art. 6 Abs. 1 S. 1 lit. b DSGVO. Die Verarbeitung ist zur Erf\u00fcllung des mit dem Nutzer geschlossen Vertrages im Rahmen des Kundenkontos erforderlich.<\/p><p>Rechtsgrundlage der \u00dcbermittlung in ein Land au\u00dferhalb des EWR ist ein Angemessenheitsbeschluss der EU-Kommission und die Zertifizierung des Anbieters unter dem EU US Privacy Framework. F\u00fcr den Fall, dass der Beschluss f\u00fcr unwirksam erkl\u00e4rt werden sollte, haben wir mit dem Anbieter Standarddatenschutzvertragsklauseln (Art. 46 Abs. 2 lit. c DSGVO) abgeschlossen.<\/p><p>Die Daten werden gel\u00f6scht, wenn der Zweck ihrer Erhebung entfallen ist und keine Aufbewahrungspflicht entgegensteht. Weitere Informationen sind in der Datenschutzerkl\u00e4rung des Anbieters unter https:\/\/www.mailgun.com\/legal\/privacy-policy\/ abrufbar.<\/p><h3>3.11.13. Mapbox<\/h3><p>Wir setzen Mapbox zur Ortung ein. Der Anbieter ist Mapbox, Inc., 50 Beale St floor 9, San Francisco, CA, USA. Der Anbieter verarbeitet Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten) und Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen) in der EU.<\/p><p>Die Rechtsgrundlage der Verarbeitung ist Art. 6 Abs. 1 S. 1 lit. a DSGVO. Die Verarbeitung erfolgt auf der Basis von Einwilligungen. Betroffene k\u00f6nnen ihre Einwilligung jederzeit widerrufen, indem sie uns z.B. unter den in unserer Datenschutzerkl\u00e4rung angegebenen Kontaktdaten kontaktieren. Der Widerruf ber\u00fchrt nicht die Rechtm\u00e4\u00dfigkeit der Verarbeitung bis zum Widerruf.<\/p><p>Die Daten werden gel\u00f6scht, wenn der Zweck ihrer Erhebung entfallen ist und keine Aufbewahrungspflicht entgegensteht. Weitere Informationen sind in der Datenschutzerkl\u00e4rung des Anbieters unter https:\/\/www.mapbox.com\/legal\/privacy abrufbar.<\/p><h1>4. Datenverarbeitung auf Social Media-Plattformen<\/h1><p>Wir sind in Social Media-Netzwerken vertreten, um dort unsere Organisation und unsere Leistungen vorzustellen. Die Betreiber dieser Netzwerke verarbeiten Daten ihrer Nutzer regelm\u00e4\u00dfig zu Werbezwecken. Unter anderem erstellen sie aus ihrem Onlineverhalten Nutzerprofile, die beispielsweise dazu verwendet werden, um auf den Seiten der Netzwerke und auch sonst im Internet Werbung zu zeigen, die den Interessen der Nutzer entspricht. Dazu speichern die Betreiber der Netzwerke Informationen zu dem Nutzungsverhalten in Cookies auf dem Rechner der Nutzer. Es ist au\u00dferdem nicht auszuschlie\u00dfen, dass die Betreiber diese Informationen mit weiteren Daten zusammenf\u00fchren. Weitere Informationen sowie Hinweise, wie Nutzer der Verarbeitung durch die Seitenbetreiber widersprechen k\u00f6nnen, erhalten Nutzer in den unten aufgef\u00fchrten Datenschutzerkl\u00e4rungen der jeweiligen Betreiber. Es kann auch sein, dass die Betreiber oder ihre Server in Nicht-EU-Staaten sitzen, so dass sie Daten dort verarbeiten. Hierdurch k\u00f6nnen sich f\u00fcr die Nutzer Risiken ergeben, z.B. weil die Durchsetzung ihrer Rechte erschwert wird oder staatliche Stellen Zugriff auf die Daten nehmen.<\/p><p>Wenn Nutzer der Netzwerke mit uns \u00fcber unsere Profile in Kontakt treten, verarbeiten wir die uns mitgeteilten Daten, um die Anfragen zu beantworten. Darin liegt unser berechtigtes Interesse, so dass Rechtsgrundlage Art. 6 Abs. 1 S. 1 lit. f DSGVO ist.<\/p><h2>4.1. Instagram<\/h2><p>Wir unterhalten ein Profil auf Instagram. Betreiber ist Meta Platforms Ireland Ltd., 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irland. Die Datenschutzerkl\u00e4rung ist hier abrufbar: https:\/\/help.instagram.com\/519522125107875.<\/p><h2>4.2. Twitter<\/h2><p>Wir unterhalten ein Profil auf Twitter. Betreiber ist Twitter Inc., 1355 Market Street, Suite 900, San Francisco, CA 94103, USA. Die Datenschutzerkl\u00e4rung ist hier abrufbar: https:\/\/twitter.com\/de\/privacy. Eine M\u00f6glichkeit, der Datenverarbeitung zu widersprechen, ergibt sich \u00fcber die Einstellungen f\u00fcr Werbeanzeigen: https:\/\/twitter.com\/personalization.<\/p><h2>4.3. LinkedIn<\/h2><p>Wir unterhalten ein Profil auf LinkedIn. Betreiber ist LinkedIn Ireland Unlimited Company, Wilton Place, Dublin 2, Irland. Die Datenschutzerkl\u00e4rung ist hier abrufbar: https:\/\/https:\/\/www.linkedin.com\/legal\/privacy-policy?_l=de_DE. Eine M\u00f6glichkeit, der Datenverarbeitung zu widersprechen, ergibt sich \u00fcber die Einstellungen f\u00fcr Werbeanzeigen: https:\/\/www.linkedin.com\/psettings\/guest-controls\/retargeting-opt-out.<\/p><h1>5. \u00c4nderungen dieser Datenschutzerkl\u00e4rung<\/h1><p>Wir behalten uns das Recht vor, diese Datenschutzerkl\u00e4rung mit Wirkung f\u00fcr die Zukunft zu \u00e4ndern. Eine aktuelle Version ist jeweils hier verf\u00fcgbar.<\/p><h1>6. Fragen und Kommentare<\/h1><p>F\u00fcr Fragen oder Kommentare bez\u00fcglich dieser Datenschutzerkl\u00e4rung stehen wir gern unter den oben angegebenen Kontaktdaten zur Verf\u00fcgung.<\/p><h1>7. Google API Compliance<\/h1><p>Wir betreiben die Anwendung Varify.io\u00ae, die auf bestimmte Google-Nutzerdaten zugreift, um unseren Kunden pr\u00e4zisere und aussagekr\u00e4ftigere Analysen im Rahmen von A\/B-Tests bereitzustellen. Unser Ziel ist es, Unternehmen fundierte Entscheidungen \u00fcber ihre Optimierungsma\u00dfnahmen zu erm\u00f6glichen.<\/p><p>Daf\u00fcr nutzen wir Datenberichte aus Google Analytics 4 (GA4), um detaillierte Vergleiche zwischen verschiedenen A\/B-Testgruppen zu erm\u00f6glichen. Die importierten Daten werden in Varify.io\u00ae weiterverarbeitet, um essenzielle Kennzahlen wie Uplift, Signifikanz und andere statistische Messwerte zu berechnen. Diese Metriken sind entscheidend f\u00fcr die Bewertung der Effektivit\u00e4t verschiedener Testvarianten und erm\u00f6glichen eine datengetriebene Entscheidungsfindung.<\/p><p>Um die Testergebnisse pr\u00e4zise zu erfassen, erstellt Varify.io\u00ae f\u00fcr jeden gestarteten A\/B-Test spezifische Audiences innerhalb von GA4. Dieser Prozess erfordert den Zugriff auf bestimmte Google API-Berechtigungen, um sicherzustellen, dass die Daten korrekt erfasst, analysiert und interpretiert werden k\u00f6nnen. Dieser Prozess erfordert den Zugriff auf folgende Google API-Berechtigungen:<\/p><ul><li>https:\/\/www.googleapis.com\/auth\/analytics.readonly<\/li><li>https:\/\/www.googleapis.com\/auth\/analytics.edit<\/li><li>https:\/\/www.googleapis.com\/auth\/analytics<\/li><\/ul><p>Wir garantieren eine transparente Nutzung der Daten, die ausschlie\u00dflich darauf ausgerichtet ist, die Ergebnisse von A\/B-Tests darzustellen und die analytischen F\u00e4higkeiten zu verbessern. Die Daten werden ausschlie\u00dflich zur Durchf\u00fchrung der beauftragten Analysefunktionen verwendet und der Zugriff erfolgt nur f\u00fcr die Dauer der aktiven Verbindung zwischen dem GA4-Konto und Varify.io\u00ae oder bis die Verbindung getrennt wird. Sollten sich \u00c4nderungen hinsichtlich des Zugriffs oder der Nutzung der Daten ergeben, werden diese in unserer Datenschutzerkl\u00e4rung aktualisiert. In diesem Fall wird eine erneute Zustimmung zu diesen \u00c4nderungen \u00fcber die API erforderlich.<\/p><p><!-- \/wp:paragraph --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Datenschutzerkl\u00e4rung Inhalt 1. Einleitung Im Folgenden informieren wir \u00fcber die Verarbeitung personenbezogener Daten bei der Nutzung unserer Website https:\/\/varify.io unserer Profile in Sozialen Medien. Personenbezogene Daten sind alle Daten, die auf eine konkrete nat\u00fcrliche Person beziehbar sind, z. B. ihr Name oder ihre IP-Adresse. 1.1. Kontaktdaten Verantwortlicher gem. Art. 4 Abs. 7 EU-Datenschutz-Grundverordnung (DSGVO) ist [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-132","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/varify.io\/en\/wp-json\/wp\/v2\/pages\/132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/varify.io\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/varify.io\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/varify.io\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/varify.io\/en\/wp-json\/wp\/v2\/comments?post=132"}],"version-history":[{"count":120,"href":"https:\/\/varify.io\/en\/wp-json\/wp\/v2\/pages\/132\/revisions"}],"predecessor-version":[{"id":47264,"href":"https:\/\/varify.io\/en\/wp-json\/wp\/v2\/pages\/132\/revisions\/47264"}],"wp:attachment":[{"href":"https:\/\/varify.io\/en\/wp-json\/wp\/v2\/media?parent=132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}