{"id":18876,"date":"2023-03-12T22:50:50","date_gmt":"2023-03-12T21:50:50","guid":{"rendered":"https:\/\/varify.io\/?p=18876"},"modified":"2026-09-02T08:11:17","modified_gmt":"2026-09-02T06:11:17","slug":"tracking-with-gtm-google-tag-manager","status":"publish","type":"post","link":"https:\/\/varify.io\/es\/userdocumentation\/tracking-with-gtm-google-tag-manager\/","title":{"rendered":"Integraci\u00f3n manual del seguimiento de Google Tag Manager"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"18876\" class=\"elementor elementor-18876\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-f85bc89 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f85bc89\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3067d42\" data-id=\"3067d42\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ccf1f91 elementor-widget elementor-widget-sidebar\" data-id=\"ccf1f91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"sidebar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<li id=\"elementor-library-3\" class=\"widget widget_elementor-library\">\t\t<div data-elementor-type=\"single-post\" data-elementor-id=\"23913\" class=\"elementor elementor-23913\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-e6fc2db elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e6fc2db\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1d76346\" data-id=\"1d76346\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a169aa elementor-widget elementor-widget-eael-advanced-search\" data-id=\"2a169aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-advanced-search.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"eael-adv-search-wrapper\">\n            <div id=\"eael-advanced-search-widget-2a169aa\" class=\"eael-advanced-search-widget\">\n                <form data-settings=\"{&quot;post_per_page&quot;:&quot;5&quot;,&quot;search_among_taxonomies&quot;:&quot;yes&quot;,&quot;search_among_sku&quot;:&quot;no&quot;,&quot;show_popular_keyword&quot;:0,&quot;show_category&quot;:1,&quot;show_content_image&quot;:1,&quot;show_search_result_all_results&quot;:1,&quot;result_on_new_tab&quot;:&quot;no&quot;,&quot;show_product_price&quot;:&quot;&quot;,&quot;include_current_page&quot;:&quot;yes&quot;,&quot;orderby&quot;:&quot;default&quot;,&quot;order&quot;:&quot;DESC&quot;,&quot;current_post_id&quot;:18876,&quot;exclude&quot;:[&quot;12&quot;,&quot;103&quot;],&quot;post_type&quot;:[&quot;post&quot;]}\" method=\"POST\" name=\"eael-advanced-search-form-2a169aa\" class=\"eael-advanced-search-form eael-advanced-search-form-style-1\">\n                    <div class=\"eael-advanced-search-wrap\">\n                        <span class=\"eael-adv-search-loader\"><\/span>\n                        <span class=\"eael-adv-search-close\"><i class=\"fas fa-times\"><\/i><\/span>\n                        <span class=\"icon \"><i class=\"fas fa-search\"><\/i><\/span>\n\n                        <input type=\"text\"\n                               placeholder=\"Suchbegriff eingeben\"\n                               class=\"eael-advanced-search\" autocomplete=\"off\" name=\"eael_advanced_search\">\n                    <\/div>\n\t\t\t\t\t                        <div class=\"eael-advance-search-select\">\n                            <span class=\"icon fas fa-chevron-down\"><\/span>\n\t\t\t\t\t\t\t<select name=\"eael-adv-search-cate-list\" class=\"eael-adv-search-cate\"><option value=''><\/option><option value='1'>Allgemein<\/option><option value='105'>Competitor comparison<\/option><option value='54'>Editor Probleme<\/option><option value='41'>Experiment erstellen<\/option><option value='52'>Experiment Start und Ausspielung<\/option><option value='43'>Experts<\/option><option value='36'>Get started<\/option><option value='108'>Integrationen<\/option><option value='21'>Nutzerdokumentation<\/option><option value='106'>Security<\/option><option value='104'>Success Stories<\/option><option value='40'>Targeting<\/option><option value='53'>Tracking und Auswertung<\/option><option value='37'>Tracking-Auswertung<\/option><option value='49'>Troubleshooting<\/option><option value='42'>Visueller Editor<\/option><option value='38'>Web Analytics Integrationen<\/option><option value='44'>Weitere Inhalte<\/option><option value='39'>Weitere Integrationen<\/option><option value='55'>WordPress<\/option><\/select>                        <\/div>\n\t\t\t\t\t                                            <button class=\"eael-advanced-search-button\">Suche<\/button>\n                                    <\/form>\n\n\t\t\t\t\n\t\t\t\t        <div class=\"eael-advanced-search-result\">\n            <div class=\"eael-advanced-search-popular-keyword\">\n\t\t\t\t<h1 class=\"eael-advanced-search-popular-keyword-text\">Popular Keywords<\/h1>                <div class=\"eael-popular-keyword-content\"><\/div>\n            <\/div>\n            <div class=\"eael-advanced-search-category\">\n\t\t\t\t<h1 class=\"eael-advanced-search-category-text\">Support article<\/h1>                <div class=\"eael-popular-category-content\"><\/div>\n            <\/div>\n\t\t\t<div class=\"eael-advanced-search-total-results-section\">\n\t\t\t\t\t\t\t\t<p class=\"eael-advanced-search-total-results-wrap\">\n\t\t\t\t\tTotal <span class=\"eael-advanced-search-total-results-count\"><\/span> Results\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n            <div class=\"eael-advanced-search-content eael-item-style-1\">\n            <\/div>\n            <div class=\"eael-advanced-search-not-found\">\n                <p>No Record Found<\/p><\/div>\n            <div class=\"eael-advanced-search-load-more\">\n\t\t\t\t<a \tclass=\"eael-advanced-search-load-more-button\"\n                \thref=\"#\">View All Results<\/a>\n            <\/div>\n        <\/div>\n\n\t\t            <\/div>\n        <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/li>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00e2fae elementor-widget elementor-widget-heading\" data-id=\"00e2fae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Manuelle Google Tag Manager Tracking-Integration<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-c42a12c e-flex e-con-boxed e-con e-parent\" data-id=\"c42a12c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2248111 elementor-widget-mobile__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"2248111\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b7b4b5 elementor-widget__width-inherit elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"4b7b4b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Diese Anleitung gilt f\u00fcr Accounts, die ihr Tracking <b>nicht bis zum 11.02.2025<\/b> eingerichtet haben. Falls dein Account bereits ein Tracking-Setup besitzt, bleibt alles wie gewohnt bestehen \u2013 es sind keine \u00c4nderungen erforderlich.<\/p><p class=\"p1\">M\u00f6chtest du dennoch auf das neue <b>Tracking Setup<\/b> umsteigen? Hier erf\u00e4hrst du, wie das geht: <span style=\"color: #333333;\"><strong><span style=\"text-decoration: underline;\"><a style=\"text-decoration: underline; color: #333333;\" href=\"https:\/\/varify.io\/de\/nutzerdokumentation\/migration-zum-tracking-wizard\/\">Migration zum Tracking Setup Wizard<\/a><\/span><\/strong><\/span><\/p><p><!-- notionvc: 7e7b21b3-3fe1-4a77-8a30-9fb90532e221 --><strong><!-- notionvc: 7e7b21b3-3fe1-4a77-8a30-9fb90532e221 --><\/strong><\/p><p><strong><!-- notionvc: 7e7b21b3-3fe1-4a77-8a30-9fb90532e221 --><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-9f60e1f elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9f60e1f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e288715\" data-id=\"e288715\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c3ffc8 elementor-widget elementor-widget-text-editor\" data-id=\"3c3ffc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #ffffff;\"><strong><span class=\"notion-enable-hover\" data-token-index=\"0\">WICHTIGER HINWEIS:<\/span><\/strong><\/span><br><span style=\"color: #ffffff;\">Die Vorgehensweise bei der Google Tag Manager Integration hat sich ge\u00e4ndert. Die bisherigen Integrationen funktionieren weiterhin wie gewohnt.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cf3b84 elementor-widget elementor-widget-table-of-contents\" data-id=\"4cf3b84\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;headings_by_tags&quot;:[&quot;h2&quot;,&quot;h3&quot;],&quot;exclude_headings_by_selector&quot;:&quot;.h2-sidebar&quot;,&quot;marker_view&quot;:&quot;bullets&quot;,&quot;icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;no_headings_message&quot;:&quot;No headings were found on this page.&quot;,&quot;hierarchical_view&quot;:&quot;yes&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t\t\t\t<h2 class=\"elementor-toc__header-title\">\n\t\t\t\tInhaltsverzeichnis\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"elementor-toc__4cf3b84\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<i class=\"elementor-toc__spinner eicon-animation-spin eicon-loading\" aria-hidden=\"true\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f3d80c elementor-widget elementor-widget-heading\" data-id=\"1f3d80c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kurz &amp; Knapp<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a049dd7 elementor-widget elementor-widget-text-editor\" data-id=\"a049dd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Im Tracking Setup Wizard hast du die M\u00f6glichkeit, das Setup manuell \u00fcber den Google Tag Manager (GTM) durchzuf\u00fchren. Daf\u00fcr sind Anpassungen im GTM erforderlich, damit Experiment-Daten an GA4 gesendet werden.<\/p><p class=\"p1\">Diese Anleitung zeigt dir Schritt f\u00fcr Schritt, wie du das Setup im Google Tag Manager korrekt einrichtest.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-a12607b e-flex e-con-boxed e-con e-parent\" data-id=\"a12607b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ede5e13 elementor-widget-mobile__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"ede5e13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec57614 elementor-widget__width-inherit elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"ec57614\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #333333;\">Wichtig f\u00fcr Shopify: Ist der Google Tag Manager \u00fcber ein Shopify Custom Pixel eingebunden, sollte folgende Tracking Integration befolgt werden: <strong><a style=\"color: #333333; text-decoration: underline;\" href=\"https:\/\/varify.io\/en\/userdocumentation\/shopify-custom-pixel-integration-via-google-tag-manager\/\">Shopify Custom Pixel Integration via Google Tag Manager<\/a><\/strong><\/span><\/p><p><!-- notionvc: 7e7b21b3-3fe1-4a77-8a30-9fb90532e221 --><strong><!-- notionvc: 7e7b21b3-3fe1-4a77-8a30-9fb90532e221 --><\/strong><\/p><p><strong><!-- notionvc: 7e7b21b3-3fe1-4a77-8a30-9fb90532e221 --><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa0c0fd elementor-widget elementor-widget-html\" data-id=\"aa0c0fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"tutorial-card\">\n  <div class=\"tutorial-card-inner\">\n    <div class=\"tutorial-card-left\">\n      <div class=\"tutorial-card-icon\">\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#FFFFFF\"><path d=\"M480-120 200-272v-240L40-600l440-240 440 240v320h-80v-276l-80 44v240L480-120Zm0-332 274-148-274-148-274 148 274 148Zm0 241 200-108v-151L480-360 280-470v151l200 108Zm0-241Zm0 90Zm0 0Z\"\/><\/svg>\n      <\/div>\n      <div>\n        <p class=\"tutorial-card-label\">Step-by-Step Tutorial<\/p>\n        <p class=\"tutorial-card-title\">Start Tracking on  Activation Event<\/p>\n      <\/div>\n    <\/div>\n    <a class=\"tutorial-card-cta\" href=\"https:\/\/app.storylane.io\/share\/fcxxrs4eq2cp\" target=\"_blank\" rel=\"noopener noreferrer\">\n  <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24px\" viewBox=\"0 -960 960 960\" width=\"24px\" fill=\"#FFFFFF\">\n    <path d=\"M320-200v-560l440 280-440 280Zm80-280Zm0 134 210-134-210-134v268Z\"\/>\n  <\/svg>\n  Tutorial starten\n<\/a>\n  <\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae65cb2 elementor-widget elementor-widget-spacer\" data-id=\"ae65cb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfeac74 elementor-widget elementor-widget-heading\" data-id=\"dfeac74\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"gtm-settings\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tracking Setup Wizard Einstellung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee5dd20 elementor-widget elementor-widget-text-editor\" data-id=\"ee5dd20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Wenn du im\u00a0Tracking Setup Wizard die manuelle Analytics-Integration \u00fcber den Google Tag Manager (GTM) w\u00e4hlst, sind zus\u00e4tzliche Anpassungen im GTM erforderlich. Ohne diese Anpassungen werden keine Tracking-Events an Google Analytics gesendet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aafd4ed elementor-widget elementor-widget-image\" data-id=\"aafd4ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1140\" height=\"753\" src=\"https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/Tracking-Wizard-Manuel-1.png\" class=\"attachment-full size-full wp-image-37283\" alt=\"\" srcset=\"https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/Tracking-Wizard-Manuel-1.png 1140w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/Tracking-Wizard-Manuel-1-300x198.png 300w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/Tracking-Wizard-Manuel-1-1024x676.png 1024w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/Tracking-Wizard-Manuel-1-768x507.png 768w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/Tracking-Wizard-Manuel-1-18x12.png 18w\" sizes=\"(max-width: 1140px) 100vw, 1140px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bac7ceb elementor-widget elementor-widget-spacer\" data-id=\"bac7ceb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1533d43 elementor-widget elementor-widget-heading\" data-id=\"1533d43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Schritt 1:  Einrichtung im Google Tag Manager<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b09ce5 elementor-widget elementor-widget-heading\" data-id=\"2b09ce5\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"new-variable\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">1. Anlegen einer neuen Data Layer Variable (VA Short)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-417b072 elementor-widget elementor-widget-text-editor\" data-id=\"417b072\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Diese Variable wird verwendet, um ein Tag den Informationen des A\/B Tests zu versehen.<\/p><ol><li>Lege eine neue Variable an: \u201cVariables\u201d &gt; \u201cNew\u201d<\/li><li>Variablentyp -&gt; \u201cData Layer Variable\u201d<\/li><li>Data Layer Variable Name -&gt; <code>varify_abTestShort<\/code> (Schreibweise obligatorisch)<\/li><li>Benenne die Variable -&gt; VA Short<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e43e936 elementor-widget elementor-widget-image\" data-id=\"e43e936\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"843\" src=\"https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM_Integration_GA4_neu_6.png\" class=\"attachment-full size-full wp-image-29800\" alt=\"\" srcset=\"https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM_Integration_GA4_neu_6.png 1280w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM_Integration_GA4_neu_6-300x198.png 300w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM_Integration_GA4_neu_6-1024x674.png 1024w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM_Integration_GA4_neu_6-768x506.png 768w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM_Integration_GA4_neu_6-18x12.png 18w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6be4da elementor-widget elementor-widget-spacer\" data-id=\"d6be4da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab72c97 elementor-widget elementor-widget-heading\" data-id=\"ab72c97\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"new-trigger\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2. Anlegen eines neuen Triggers (Varify.io - Event)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a85b6b3 elementor-widget elementor-widget-text-editor\" data-id=\"a85b6b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Der Trigger ist das entscheidende Ereignis, dass die \u00dcbermittlung der Daten zum Analytics-System anst\u00f6\u00dft.<\/p><ol><li>Name des Triggers: z. B. &#8222;Varify.io \u2013 event\u201d<\/li><li>Triggertyp: \u201cBenutzerdefiniertes Ereignis\u201d<\/li><li>Ereignisname: <code>varify<\/code> (Schreibweise obligatorisch)<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23a9e7b elementor-widget elementor-widget-image\" data-id=\"23a9e7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"843\" src=\"https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM_Integration_GA4_neu_2.png\" class=\"attachment-full size-full wp-image-29429\" alt=\"\" srcset=\"https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM_Integration_GA4_neu_2.png 1280w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM_Integration_GA4_neu_2-300x198.png 300w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM_Integration_GA4_neu_2-1024x674.png 1024w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM_Integration_GA4_neu_2-768x506.png 768w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM_Integration_GA4_neu_2-18x12.png 18w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f4b3c3 elementor-widget elementor-widget-spacer\" data-id=\"3f4b3c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0b36be elementor-widget elementor-widget-heading\" data-id=\"a0b36be\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"new-tracking-linker\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3. Anlegen eines neuen GTM Tags (Varify.io - GA4 Tracking Linker)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2238f49 elementor-widget elementor-widget-text-editor\" data-id=\"2238f49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tags sind Code-Schnipsel, welche die in den Variablen gespeicherten Werte zu deinem Analytics-Tool senden, wie z.B. Google Analytics. Lege nun ein sochles Tag an, um die Werte der erstellte Variable an Google Alytics zu senden.<\/p><ol><li>Name des Tags: \u201cVarify.io \u2013 GA4 Tracking Linker\u201d<\/li><li>Konfigurations-Tag: [Dein vorhandenes GA4 Tag verwenden]<\/li><li>Ereignisname: z. B. \u201cAbtesting\u201d<\/li><li>Parametername: <code>varify_abTestShort<\/code> (Schreibweise Obligatorisch)<\/li><li>Werte: <code>{{VA Short}}<\/code> (Die in Schritt 1 erstellte Variable)<\/li><li>Trigger: \u201cVarify.io &#8211; event\u201d (Der in Schritt 2 erstellte Trigger)<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b19c233 elementor-widget elementor-widget-image\" data-id=\"b19c233\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"1133\" src=\"https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM_Integration_GA4_neu_7.png\" class=\"attachment-full size-full wp-image-29799\" alt=\"\" srcset=\"https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM_Integration_GA4_neu_7.png 1280w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM_Integration_GA4_neu_7-300x266.png 300w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM_Integration_GA4_neu_7-1024x906.png 1024w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM_Integration_GA4_neu_7-768x680.png 768w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM_Integration_GA4_neu_7-14x12.png 14w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efb92fa elementor-widget elementor-widget-spacer\" data-id=\"efb92fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-064eb28 elementor-widget elementor-widget-heading\" data-id=\"064eb28\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"gtm-publish\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4. GTM Container ver\u00f6ffentlichen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d23976 elementor-widget elementor-widget-text-editor\" data-id=\"8d23976\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Damit deine Anpassungen im Google Tag Manager auch auf deiner Website funktionieren ist es wichtig, die \u00c4nderungen zu ver\u00f6ffentlichen.<\/p><p>Gehe dazu im Tag Manager links auf &#8222;\u00dcbersicht&#8220;. Hier siehst du alle Elemente, die du eben erstellt hast im \u00dcberblick.<\/p><p>Klicke zum ver\u00f6ffentlichen oben rechts auf den blauen &#8222;Ver\u00f6ffentlichen&#8220; Button und best\u00e4tige diese. Ab jetzt ist das Tag live und sendet die Daten an dein Google Analytics.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc3b735 elementor-widget elementor-widget-image\" data-id=\"cc3b735\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"268\" src=\"https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/image-1966.png\" class=\"attachment-full size-full wp-image-36152\" alt=\"\" srcset=\"https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/image-1966.png 1280w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/image-1966-300x63.png 300w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/image-1966-1024x214.png 1024w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/image-1966-768x161.png 768w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/image-1966-18x4.png 18w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99944ff elementor-widget elementor-widget-spacer\" data-id=\"99944ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f536c01 elementor-widget elementor-widget-heading\" data-id=\"f536c01\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"data-transfer-ga4\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Schritt 2: \u00dcbermittlung der Daten an GA4<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c959222 elementor-widget elementor-widget-heading\" data-id=\"c959222\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"user-consent\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Senden der Daten mit User Consent<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd9a379 elementor-widget elementor-widget-text-editor\" data-id=\"dd9a379\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Du kannst die Experiment Daten mit oder ohne User Consent an GA4 senden. Wenn Google Analytics 4 Daten bereits nur per User Consent senden, solltest du die Varify Daten ebenfalls nur \u00fcber User Consent schicken. Wie das funktioniert findest du hier: <strong><a href=\"https:\/\/varify.io\/de\/nutzerdokumentation\/tracking-via-consent\/\">Senden der Daten mit User Consent<\/a><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e726a3 elementor-widget elementor-widget-heading\" data-id=\"3e726a3\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"no-consent\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Senden der Daten ohne User Consent<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a43369e elementor-widget elementor-widget-text-editor\" data-id=\"a43369e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die nachfolgenden Schritte beschreiben das Senden der Daten an GA4 <b>ohne User Consent<\/b>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e1fdd2 elementor-widget elementor-widget-heading\" data-id=\"2e1fdd2\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"tracking-activation-script\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">1. Einstellung: Start Tracking on Activation Event<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c07af16 elementor-widget elementor-widget-text-editor\" data-id=\"c07af16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"0\" data-end=\"120\">Unter &#8222;Advanced Setup&#8220; findest du die Einstellung &#8222;Start Tracking on Activation Event&#8220;, die standardm\u00e4\u00dfig aktiviert ist.<\/p><ul data-start=\"122\" data-end=\"836\"><li data-start=\"122\" data-end=\"602\"><p data-start=\"124\" data-end=\"602\">&#8222;Aktiviert (Standard)&#8220;: Varify Tracking Events werden erst in den Datalayer gepusht, nachdem das &#8222;Activate Tracking Script&#8220; ausgef\u00fchrt wurde. Dadurch wird sichergestellt, dass Events erst nach vollst\u00e4ndiger GA4-Konfiguration gesendet werden und \u201cNot Set\u201d-Sessions vermieden werden. &#8222;Wichtig&#8220;: Das &#8222;Activate Tracking Script&#8220; muss als Custom HTML Tag in GTM hinterlegt werden. Ohne dieses Script werden keine Events an GA4 gesendet. Folge dazu den Schritten 2\u20134 der GTM-Anleitung.<\/p><\/li><li data-start=\"606\" data-end=\"836\"><p data-start=\"608\" data-end=\"836\">&#8222;Deaktiviert&#8220;: Events werden sofort beim Laden der Variante in den Datalayer geschrieben. Es kann dazu f\u00fchren, dass nicht alle Nutzer korrekt in GA4 erfasst werden, falls die GA4-Konfiguration noch nicht vollst\u00e4ndig geladen ist.<\/p><\/li><\/ul><p data-start=\"838\" data-end=\"1587\" data-is-last-node=\"\" data-is-only-node=\"\">Zus\u00e4tzlich wird bei aktiviertem &#8222;Start Tracking on Activation Event&#8220; die Option &#8222;Keep users in variation&#8220; angezeigt. Ist diese aktiviert, werden Nutzer ohne ausgef\u00fchrtes &#8222;Tracking Activation Script&#8220; im &#8222;Session Storage&#8220; gespeichert, wodurch sie w\u00e4hrend der Session dieselbe Variante sehen. Nach Ausf\u00fchrung des Scripts wird die Information vom &#8222;Session Storage&#8220; in den &#8222;Local Storage&#8220; \u00fcbertragen und der Nutzer dauerhaft einer Variante zugeordnet. Diese Option sollte besonders dann eingesetzt werden, wenn beispielsweise auf der Webseite gesurft werden kann, ohne dass man mit dem Cookie-Banner interagieren muss, da die User w\u00e4hrend der Session dauerhaft der initial zugeordneten Variante zugeordnet bleiben, auch ohne Zustimmung zum Cookie-Banner.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b01fd6 elementor-widget elementor-widget-image\" data-id=\"9b01fd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2308\" height=\"1524\" src=\"https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/Activate-tracking-script-setting-1.png\" class=\"attachment-full size-full wp-image-44474\" alt=\"\" srcset=\"https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/Activate-tracking-script-setting-1.png 2308w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/Activate-tracking-script-setting-1-300x198.png 300w\" sizes=\"(max-width: 2308px) 100vw, 2308px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-695ac07 elementor-widget elementor-widget-spacer\" data-id=\"695ac07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a84496 elementor-widget elementor-widget-heading\" data-id=\"2a84496\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2. Erstelle ein neues Custom HTML Tag im GTM<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-557ca68 elementor-widget elementor-widget-text-editor\" data-id=\"557ca68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li>Gehe in den Google Tag Manager zu Tags und klicke auf neu. Lege hier nun ein neues Custom HTML Tag an.<\/li><li>Benenne das Tag: &#8222;Varify Activate Tracking&#8220;<\/li><li>F\u00fcge folgenden Code in das HTML Feld ein:<\/li><li>Speichere den Tag ab. Best\u00e4tige, dass der Tag ohne Trigger\u00a0gespeichert werden soll.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fbdf2b elementor-widget elementor-widget-code-highlight\" data-id=\"8fbdf2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"code-highlight.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"prismjs-default copy-to-clipboard \">\n\t\t\t<pre data-line=\"\" class=\"highlight-height language-javascript line-numbers\">\n\t\t\t\t<code readonly=\"true\" class=\"language-javascript\">\n\t\t\t\t\t<xmp><script>\n  if (window.varify && typeof window.varify.setTracking === 'function') {\n    window.varify.setTracking(true);\n  } else {\n    window.addEventListener('varify:loaded', function () {\n      window.varify.setTracking(true);\n    });\n  }\n<\/script><\/xmp>\n\t\t\t\t<\/code>\n\t\t\t<\/pre>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-5b5de8d e-flex e-con-boxed e-con e-parent\" data-id=\"5b5de8d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-54adae1 elementor-widget-mobile__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"54adae1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0739f7 elementor-widget__width-inherit elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"b0739f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\"><b>Seit dem 29.10.2025 verwenden wir ein aktualisiertes Activate Tracking Script.<br \/><\/b><b><\/b>Alle zuvor implementierten Skripte bleiben jedoch weiterhin g\u00fcltig und funktionieren ohne Anpassungen.<\/p><p><!-- notionvc: 7e7b21b3-3fe1-4a77-8a30-9fb90532e221 --><strong><!-- notionvc: 7e7b21b3-3fe1-4a77-8a30-9fb90532e221 --><\/strong><\/p><p><strong><!-- notionvc: 7e7b21b3-3fe1-4a77-8a30-9fb90532e221 --><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9935357 elementor-widget elementor-widget-image\" data-id=\"9935357\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1128\" height=\"594\" src=\"https:\/\/varify.io\/wp-content\/uploads\/2025\/04\/Bildschirmfoto-2025-10-29-um-13.57.09.png\" class=\"attachment-full size-full wp-image-43462\" alt=\"\" srcset=\"https:\/\/varify.io\/wp-content\/uploads\/2025\/04\/Bildschirmfoto-2025-10-29-um-13.57.09.png 1128w, https:\/\/varify.io\/wp-content\/uploads\/2025\/04\/Bildschirmfoto-2025-10-29-um-13.57.09-300x158.png 300w, https:\/\/varify.io\/wp-content\/uploads\/2025\/04\/Bildschirmfoto-2025-10-29-um-13.57.09-1024x539.png 1024w, https:\/\/varify.io\/wp-content\/uploads\/2025\/04\/Bildschirmfoto-2025-10-29-um-13.57.09-768x404.png 768w, https:\/\/varify.io\/wp-content\/uploads\/2025\/04\/Bildschirmfoto-2025-10-29-um-13.57.09-18x9.png 18w\" sizes=\"(max-width: 1128px) 100vw, 1128px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37ae026 elementor-widget elementor-widget-spacer\" data-id=\"37ae026\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cbe535 elementor-widget elementor-widget-heading\" data-id=\"9cbe535\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3. Google Tag Konfiguration Tag anpassen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c4f3c4 elementor-widget elementor-widget-text-editor\" data-id=\"7c4f3c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol>\n \t<li>Gehe nun zu deinem GA4 Konfigurationstag und \u00f6ffne es. <i>Hinweis: Am einfachsten kannst du es finden, indem du zu deinen Tags navigierst und mit Strg+F nach &#8222;Google Tag&#8220; suchst<\/i><\/li>\n<\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5053c62 elementor-widget elementor-widget-image\" data-id=\"5053c62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1695\" height=\"409\" src=\"https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/Bildschirmfoto-2025-01-30-um-10.14.47.png\" class=\"attachment-full size-full wp-image-35648\" alt=\"\" srcset=\"https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/Bildschirmfoto-2025-01-30-um-10.14.47.png 1695w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/Bildschirmfoto-2025-01-30-um-10.14.47-300x72.png 300w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/Bildschirmfoto-2025-01-30-um-10.14.47-1024x247.png 1024w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/Bildschirmfoto-2025-01-30-um-10.14.47-768x185.png 768w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/Bildschirmfoto-2025-01-30-um-10.14.47-1536x371.png 1536w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/Bildschirmfoto-2025-01-30-um-10.14.47-18x4.png 18w\" sizes=\"(max-width: 1695px) 100vw, 1695px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-702acac elementor-widget elementor-widget-text-editor\" data-id=\"702acac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol start=\"2\"><li>Klicke in den Bereich\u00a0 Tag Configuration und w\u00e4hle Advanced Settings und Tag Sequencing.<\/li><li>Klicke nun auf &#8222;Fire a tag after GA4 Config (The GA4 config tag) fires&#8220;<\/li><li>W\u00e4hle das eben erstellte Varify Activate Tracking Tag aus.<\/li><li>Klicke den Hacken darunter an &#8222;Don&#8217;t fire Varify Activate Tracking\u00a0if\u00a0GA4 Config fails or is paused&#8220;<\/li><li>Speichere die Tag Anpassung<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5ea758 elementor-widget elementor-widget-image\" data-id=\"c5ea758\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1131\" height=\"1118\" src=\"https:\/\/varify.io\/wp-content\/uploads\/2025\/02\/Bildschirmfoto-2025-02-11-um-17.18.42.png\" class=\"attachment-full size-full wp-image-36199\" alt=\"\" srcset=\"https:\/\/varify.io\/wp-content\/uploads\/2025\/02\/Bildschirmfoto-2025-02-11-um-17.18.42.png 1131w, https:\/\/varify.io\/wp-content\/uploads\/2025\/02\/Bildschirmfoto-2025-02-11-um-17.18.42-300x297.png 300w, https:\/\/varify.io\/wp-content\/uploads\/2025\/02\/Bildschirmfoto-2025-02-11-um-17.18.42-1024x1012.png 1024w, https:\/\/varify.io\/wp-content\/uploads\/2025\/02\/Bildschirmfoto-2025-02-11-um-17.18.42-768x759.png 768w, https:\/\/varify.io\/wp-content\/uploads\/2025\/02\/Bildschirmfoto-2025-02-11-um-17.18.42-12x12.png 12w\" sizes=\"(max-width: 1131px) 100vw, 1131px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42635f4 elementor-widget elementor-widget-spacer\" data-id=\"42635f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4baeaf1 elementor-widget elementor-widget-heading\" data-id=\"4baeaf1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4. GTM Container ver\u00f6ffentlichen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1d652d elementor-widget elementor-widget-text-editor\" data-id=\"b1d652d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Damit deine Anpassungen im Google Tag Manager auch auf deiner Website funktionieren ist es wichtig, die \u00c4nderungen zu ver\u00f6ffentlichen.<\/p><p>Gehe dazu im Tag Manager links auf &#8222;\u00dcbersicht&#8220;. Hier siehst du alle Elemente, die du eben erstellt hast im \u00dcberblick.<\/p><p>Klicke zum ver\u00f6ffentlichen oben rechts auf den blauen &#8222;Ver\u00f6ffentlichen&#8220; Button und best\u00e4tige diese. Ab jetzt ist das Tag live und sendet die Daten an dein Google Analytics.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bbe7b8 elementor-widget elementor-widget-image\" data-id=\"7bbe7b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"268\" src=\"https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/image-1966.png\" class=\"attachment-full size-full wp-image-36152\" alt=\"\" srcset=\"https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/image-1966.png 1280w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/image-1966-300x63.png 300w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/image-1966-1024x214.png 1024w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/image-1966-768x161.png 768w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/image-1966-18x4.png 18w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-975c4d9 elementor-widget elementor-widget-spacer\" data-id=\"975c4d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-844228d elementor-widget elementor-widget-heading\" data-id=\"844228d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Schritt 3: Einrichtung einer Custom Dimension in GA4<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-3f3dcdc e-flex e-con-boxed e-con e-parent\" data-id=\"3f3dcdc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e9df448 elementor-widget-mobile__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"e9df448\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-6749232 e-con-full e-flex e-con e-child\" data-id=\"6749232\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fe78035 elementor-widget__width-inherit elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"fe78035\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>WICHTIGER HINWEIS:<\/strong> Die Custom Dimension muss nur dann manuell erstellt werden, wenn dein Varify-Konto nicht \u00fcber den Google Authenticator mit Google Analytics 4 verbunden werden soll.<\/p><p><strong><!-- notionvc: 7e7b21b3-3fe1-4a77-8a30-9fb90532e221 --><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-daf3e86 elementor-widget elementor-widget-image\" data-id=\"daf3e86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"804\" height=\"91\" src=\"https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/Bildschirmfoto-2025-02-11-um-11.41.56.png\" class=\"attachment-full size-full wp-image-36153\" alt=\"\" srcset=\"https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/Bildschirmfoto-2025-02-11-um-11.41.56.png 804w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/Bildschirmfoto-2025-02-11-um-11.41.56-300x34.png 300w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/Bildschirmfoto-2025-02-11-um-11.41.56-768x87.png 768w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/Bildschirmfoto-2025-02-11-um-11.41.56-18x2.png 18w\" sizes=\"(max-width: 804px) 100vw, 804px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f02518 elementor-widget elementor-widget-text-editor\" data-id=\"3f02518\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Abschlie\u00dfend ist es n\u00f6tig, eine Custom Dimension in Google Analytics anzulegen. Gehe dabei wie folgt vor:<\/p>\n<ol>\n<li>\u00d6ffne deine GA4-Einstellungen und w\u00e4hle den Men\u00fcpunkt \u201cCustom Definitions\u201d<\/li>\n<\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f826131 elementor-widget elementor-widget-image\" data-id=\"f826131\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1230\" src=\"https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM-CustomDimension1-2048x1299-1.png\" class=\"attachment-full size-full wp-image-25595\" alt=\"\" srcset=\"https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM-CustomDimension1-2048x1299-1.png 2048w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM-CustomDimension1-2048x1299-1-300x180.png 300w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM-CustomDimension1-2048x1299-1-1024x615.png 1024w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM-CustomDimension1-2048x1299-1-768x461.png 768w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM-CustomDimension1-2048x1299-1-1536x923.png 1536w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM-CustomDimension1-2048x1299-1-18x12.png 18w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c72b13 elementor-widget elementor-widget-text-editor\" data-id=\"4c72b13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol start=\"2\"><li>Erstelle eine neue Custom Dimension (\u201cCreate custom dimension\u201d)<\/li><li>W\u00e4hle einen Dimensionsnamen: Varify AB Test (Schreibweise obligatorisch)<\/li><li>W\u00e4hle den Ereignisparameter: varify_abTestShort (Achte darauf, dass du den Ereignisparameter in der korrekten Schreibweise angibst.)<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-491ea78 elementor-widget elementor-widget-image\" data-id=\"491ea78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1162\" height=\"288\" src=\"https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM_Integration_GA4_neu_4.png\" class=\"attachment-full size-full wp-image-29427\" alt=\"\" srcset=\"https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM_Integration_GA4_neu_4.png 1162w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM_Integration_GA4_neu_4-300x74.png 300w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM_Integration_GA4_neu_4-1024x254.png 1024w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM_Integration_GA4_neu_4-768x190.png 768w, https:\/\/varify.io\/wp-content\/uploads\/2023\/03\/GTM_Integration_GA4_neu_4-18x4.png 18w\" sizes=\"(max-width: 1162px) 100vw, 1162px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-a17a957 e-flex e-con-boxed e-con e-parent\" data-id=\"a17a957\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-96b4613 elementor-widget-mobile__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"96b4613\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-799f0c9 elementor-widget__width-inherit elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"799f0c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><span class=\"notion-enable-hover\" data-token-index=\"0\">Wichtiger Hinweis:\u00a0<\/span><\/strong>Du wirst den Ereignisparameter \u201cvarify_abTestShort\u201d unter der benutzerdefinierte Definition erst dann ausw\u00e4hlen k\u00f6nnen, sobald GA4 die ersten Testdaten von dir empfangen hat. Danach kann es nochmal bis zu 24 Stunden dauern, bis du den Wert im Dropdown findest. <b>Du kannst den Parameter trotzdem manuell eintragen, achte dabei aber auf die richtige Schreibweise.<\/b><\/p><p><!-- notionvc: 7e7b21b3-3fe1-4a77-8a30-9fb90532e221 --><strong><!-- notionvc: 7e7b21b3-3fe1-4a77-8a30-9fb90532e221 --><\/strong><\/p><p><strong><!-- notionvc: 7e7b21b3-3fe1-4a77-8a30-9fb90532e221 --><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e3f7b6 elementor-widget elementor-widget-spacer\" data-id=\"4e3f7b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-075902b elementor-widget elementor-widget-heading\" data-id=\"075902b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Anzeigen der A\/B-Testdaten in Varify.io<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2751b45 elementor-widget elementor-widget-text-editor\" data-id=\"2751b45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mit der Varify.io &lt;&gt; Google Analytics 4 Connection kannst du deine Ergebnisse ganz einfach direkt in deinem Varify.io Dashboard anzeigen. Wie das geht erf\u00e4hrst du hier:\u00a0<a href=\"https:\/\/varify.io\/de\/userdocumentation\/ga4-connection\/\" data-wplink-edit=\"true\">Zur Ergebnisauswertung in Varify.io<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35de890 elementor-widget elementor-widget-heading\" data-id=\"35de890\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Anzeigen der A\/B-Testdaten in GA4<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9597f09 elementor-widget elementor-widget-text-editor\" data-id=\"9597f09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Daten der Varianten deines A\/B Tests kannst du in GA4 mit der Explorativen Datenanalyse auswerten. Weitere Informationen findest du hier: <a href=\"https:\/\/varify.io\/nutzerdokumentation\/ergebnisauswertung-in-ga-4\/\">Zur Ergebnisauswertung in GA4<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f8dda9 elementor-widget elementor-widget-spacer\" data-id=\"6f8dda9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1db956a\" data-id=\"1db956a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eaf0808 elementor-widget elementor-widget-sidebar\" data-id=\"eaf0808\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"sidebar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<li id=\"elementor-library-2\" class=\"widget widget_elementor-library\">\t\t<div data-elementor-type=\"single-post\" data-elementor-id=\"23790\" class=\"elementor elementor-23790\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-e4670c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e4670c6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-231dec3\" data-id=\"231dec3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67c00f2 elementor-widget elementor-widget-heading\" data-id=\"67c00f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/varify.io\/de\/userdocumentation\/\">Nutzerdokumentation<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b87b89c elementor-widget elementor-widget-n-accordion\" data-id=\"b87b89c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1930\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-1930\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Erste Schritte <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-1930\" class=\"elementor-element elementor-element-3819167 e-con-full e-flex e-con e-child\" data-id=\"3819167\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-1930\" class=\"elementor-element elementor-element-42ba248 e-flex e-con-boxed e-con e-child\" data-id=\"42ba248\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-805dc5d elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"805dc5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;dropdown&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-chevron-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-805dc5d\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-45448\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/how-varify-works\/\" class=\"elementor-item\" tabindex=\"-1\">So funktioniert Varify.io<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-23830\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/varify-snippet-implementation\/\" class=\"elementor-item\" tabindex=\"-1\">Varify Snippet \u2013 Implementierung<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40608\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/tracking-setup\/\" class=\"elementor-item\" tabindex=\"-1\">Tracking einrichten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-25116\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/start-an-a-a-test\/\" class=\"elementor-item\" tabindex=\"-1\">Starte einen A\/A Test und \u00fcberpr\u00fcfe das Tracking\u200b<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40572\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/a-b-testing-experiment-creation\/\" class=\"elementor-item\" tabindex=\"-1\">Experiment erstellen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-25866\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/chrome-browser-extension\/\" class=\"elementor-item\" tabindex=\"-1\">Chrome Browser Erweiterung<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-45578\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/best-practice\/\" class=\"elementor-item\" tabindex=\"-1\">Best Practice<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-47082\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/cro-ai-audit\/\" class=\"elementor-item\" tabindex=\"-1\">CRO AI Audit<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1931\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1931\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Tracking &amp; Web Analytics Integrationen <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-1931\" class=\"elementor-element elementor-element-93f153a e-con-full e-flex e-con e-child\" data-id=\"93f153a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bacbb76 elementor-nav-menu__align-start elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"bacbb76\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-text e--animation-none\">\n\t\t\t\t<ul id=\"menu-1-bacbb76\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40606\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/tracking-setup\/\" class=\"elementor-item\">Tracking mit Varify<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33939\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/tracking-with-gtm-google-tag-manager\/\" class=\"elementor-item\">Manuelle Google Tag Manager Tracking-Integration<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40509\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/automatic-ga4-tracking-integration\/\" class=\"elementor-item\">Automatische GA4 Tracking Integration<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-47784\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/custom-click-events\/\" class=\"elementor-item\">Benutzerdefinierte Klick Events anlegen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-35528\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/shopify-custom-pixel-integration-via-google-tag-manager\/\" class=\"elementor-item\">Shopify Custom Pixel Integration via Google Tag Manager<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40510\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/shopify-tracking\/\" class=\"elementor-item\">Shopify Tracking<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-42108\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/bigquery\/\" class=\"elementor-item\">BigQuery<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40959\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/posthog-tracking\/\" class=\"elementor-item\">PostHog Auswertungen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33941\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/etracker-integration\/\" class=\"elementor-item\">etracker Integration<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-47809\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/econda-integration\/\" class=\"elementor-item\">econda Integration<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33940\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/matomo-integration-via-matomo-tag-manager\/\" class=\"elementor-item\">Matomo \u2013 Integration via Matomo Tag Manager<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33942\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/piwik-pro-integration\/\" class=\"elementor-item\">Piwik Pro Integration<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-37218\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/tracking-via-consent\/\" class=\"elementor-item\">Consent \u2013 Tracking via Consent<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40607\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/advanced-setup-options\/\" class=\"elementor-item\">Advanced Settings<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-bacbb76\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40606\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/tracking-setup\/\" class=\"elementor-item\" tabindex=\"-1\">Tracking mit Varify<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33939\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/tracking-with-gtm-google-tag-manager\/\" class=\"elementor-item\" tabindex=\"-1\">Manuelle Google Tag Manager Tracking-Integration<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40509\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/automatic-ga4-tracking-integration\/\" class=\"elementor-item\" tabindex=\"-1\">Automatische GA4 Tracking Integration<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-47784\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/custom-click-events\/\" class=\"elementor-item\" tabindex=\"-1\">Benutzerdefinierte Klick Events anlegen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-35528\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/shopify-custom-pixel-integration-via-google-tag-manager\/\" class=\"elementor-item\" tabindex=\"-1\">Shopify Custom Pixel Integration via Google Tag Manager<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40510\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/shopify-tracking\/\" class=\"elementor-item\" tabindex=\"-1\">Shopify Tracking<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-42108\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/bigquery\/\" class=\"elementor-item\" tabindex=\"-1\">BigQuery<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40959\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/posthog-tracking\/\" class=\"elementor-item\" tabindex=\"-1\">PostHog Auswertungen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33941\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/etracker-integration\/\" class=\"elementor-item\" tabindex=\"-1\">etracker Integration<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-47809\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/econda-integration\/\" class=\"elementor-item\" tabindex=\"-1\">econda Integration<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33940\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/matomo-integration-via-matomo-tag-manager\/\" class=\"elementor-item\" tabindex=\"-1\">Matomo \u2013 Integration via Matomo Tag Manager<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33942\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/piwik-pro-integration\/\" class=\"elementor-item\" tabindex=\"-1\">Piwik Pro Integration<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-37218\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/tracking-via-consent\/\" class=\"elementor-item\" tabindex=\"-1\">Consent \u2013 Tracking via Consent<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40607\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/advanced-setup-options\/\" class=\"elementor-item\" tabindex=\"-1\">Advanced Settings<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1932\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1932\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Experiment erstellen <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-1932\" class=\"elementor-element elementor-element-4c0f900 e-con-full e-flex e-con e-child\" data-id=\"4c0f900\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7bf1a99 elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"7bf1a99\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-text e--animation-none\">\n\t\t\t\t<ul id=\"menu-1-7bf1a99\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33931\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/a-b-testing-experiment-creation\/\" class=\"elementor-item\">Experiment erstellen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-47097\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/prompt-based-experiments\/\" class=\"elementor-item\">Prompt Based Experiments (PBX)<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33932\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/a-b-testing-quality-assurance\/\" class=\"elementor-item\">Qualit\u00e4tssicherung<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40569\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/start-and-stop-experiments\/\" class=\"elementor-item\">Starten und stoppen von Experimenten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-45968\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/schedule-experiments\/\" class=\"elementor-item\">Zeitgesteuertes Starten und Stoppen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40198\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/redirect-and-split-url-testing\/\" class=\"elementor-item\">Redirect &#038; Split URL Testing<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33933\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/duplicate-variations\/\" class=\"elementor-item\">Variante duplizieren<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33935\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/experiment-with-multiple-variations\/\" class=\"elementor-item\">Experiment mit mehreren Varianten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33936\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/rename-experiments-and-variations\/\" class=\"elementor-item\">Umbenennen von Experimenten und Varianten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-35042\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/create-multi-page-experiments\/\" class=\"elementor-item\">Multi-Page Experiment erstellen<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-7bf1a99\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33931\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/a-b-testing-experiment-creation\/\" class=\"elementor-item\" tabindex=\"-1\">Experiment erstellen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-47097\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/prompt-based-experiments\/\" class=\"elementor-item\" tabindex=\"-1\">Prompt Based Experiments (PBX)<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33932\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/a-b-testing-quality-assurance\/\" class=\"elementor-item\" tabindex=\"-1\">Qualit\u00e4tssicherung<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40569\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/start-and-stop-experiments\/\" class=\"elementor-item\" tabindex=\"-1\">Starten und stoppen von Experimenten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-45968\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/schedule-experiments\/\" class=\"elementor-item\" tabindex=\"-1\">Zeitgesteuertes Starten und Stoppen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40198\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/redirect-and-split-url-testing\/\" class=\"elementor-item\" tabindex=\"-1\">Redirect &#038; Split URL Testing<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33933\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/duplicate-variations\/\" class=\"elementor-item\" tabindex=\"-1\">Variante duplizieren<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33935\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/experiment-with-multiple-variations\/\" class=\"elementor-item\" tabindex=\"-1\">Experiment mit mehreren Varianten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33936\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/rename-experiments-and-variations\/\" class=\"elementor-item\" tabindex=\"-1\">Umbenennen von Experimenten und Varianten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-35042\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/create-multi-page-experiments\/\" class=\"elementor-item\" tabindex=\"-1\">Multi-Page Experiment erstellen<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1933\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1933\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Targeting <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-1933\" class=\"elementor-element elementor-element-e403a77 e-con-full e-flex e-con e-child\" data-id=\"e403a77\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d08d6d7 elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"d08d6d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-text e--animation-none\">\n\t\t\t\t<ul id=\"menu-1-d08d6d7\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-24547\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/audience-targeting\/\" class=\"elementor-item\">Audience Targeting<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-42062\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/mutual-exclusion-of-experiments\/\" class=\"elementor-item\">Gegenseitiger Ausschluss von Experimenten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-26934\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/page-targeting\/\" class=\"elementor-item\">Page Targeting<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-d08d6d7\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-24547\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/audience-targeting\/\" class=\"elementor-item\" tabindex=\"-1\">Audience Targeting<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-42062\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/mutual-exclusion-of-experiments\/\" class=\"elementor-item\" tabindex=\"-1\">Gegenseitiger Ausschluss von Experimenten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-26934\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/page-targeting\/\" class=\"elementor-item\" tabindex=\"-1\">Page Targeting<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1934\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1934\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Reporting &amp; Auswertung <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-1934\" class=\"elementor-element elementor-element-66d7d7c e-con-full e-flex e-con e-child\" data-id=\"66d7d7c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8ea8bf7 elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"8ea8bf7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-text e--animation-none\">\n\t\t\t\t<ul id=\"menu-1-8ea8bf7\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-47757\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/evaluate-experiments-in-varify-io\/\" class=\"elementor-item\">Experimente auswerten in Varify.io<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-34874\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/segments-and-filter\/\" class=\"elementor-item\">Reports segmentieren und filtern<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40782\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/share-report\/\" class=\"elementor-item\">Report teilen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-30433\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/ga4-audience-evaluation\/\" class=\"elementor-item\">Audiencebasierte Auswertung in GA4<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-23805\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/result-evaluation-in-ga-4\/\" class=\"elementor-item\">Segmentbasierte Auswertung in GA 4<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-42107\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/bigquery\/\" class=\"elementor-item\">BigQuery<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-41178\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/posthog-tracking\/\" class=\"elementor-item\">PostHog Tracking<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-43502\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/export-experiment-results\/\" class=\"elementor-item\">Exportieren der Experimentergebnisse aus Varify<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-28921\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/matomo-result-evaluation\/\" class=\"elementor-item\">Matomo \u2013 Ergebnisauswertung\u200b<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-31116\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/etracker-evaluation\/\" class=\"elementor-item\">etracker Auswertung<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-25005\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/significance-calculation\/\" class=\"elementor-item\">Signifikanz berechnen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-26075\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/evaluate-custom-events-in-explorative-reports\/\" class=\"elementor-item\">Custom Events in explorativen Reports auswerten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-34870\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/ga4-cross-domain-tracking\/\" class=\"elementor-item\">GA4 \u2013 Cross-Domain Tracking<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-8ea8bf7\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-47757\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/evaluate-experiments-in-varify-io\/\" class=\"elementor-item\" tabindex=\"-1\">Experimente auswerten in Varify.io<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-34874\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/segments-and-filter\/\" class=\"elementor-item\" tabindex=\"-1\">Reports segmentieren und filtern<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40782\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/share-report\/\" class=\"elementor-item\" tabindex=\"-1\">Report teilen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-30433\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/ga4-audience-evaluation\/\" class=\"elementor-item\" tabindex=\"-1\">Audiencebasierte Auswertung in GA4<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-23805\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/result-evaluation-in-ga-4\/\" class=\"elementor-item\" tabindex=\"-1\">Segmentbasierte Auswertung in GA 4<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-42107\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/bigquery\/\" class=\"elementor-item\" tabindex=\"-1\">BigQuery<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-41178\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/posthog-tracking\/\" class=\"elementor-item\" tabindex=\"-1\">PostHog Tracking<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-43502\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/export-experiment-results\/\" class=\"elementor-item\" tabindex=\"-1\">Exportieren der Experimentergebnisse aus Varify<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-28921\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/matomo-result-evaluation\/\" class=\"elementor-item\" tabindex=\"-1\">Matomo \u2013 Ergebnisauswertung\u200b<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-31116\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/etracker-evaluation\/\" class=\"elementor-item\" tabindex=\"-1\">etracker Auswertung<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-25005\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/significance-calculation\/\" class=\"elementor-item\" tabindex=\"-1\">Signifikanz berechnen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-26075\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/evaluate-custom-events-in-explorative-reports\/\" class=\"elementor-item\" tabindex=\"-1\">Custom Events in explorativen Reports auswerten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-34870\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/ga4-cross-domain-tracking\/\" class=\"elementor-item\" tabindex=\"-1\">GA4 \u2013 Cross-Domain Tracking<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1935\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1935\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Visueller Editor <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-1935\" class=\"elementor-element elementor-element-20b5ed4 e-con-full e-flex e-con e-child\" data-id=\"20b5ed4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e781b2c elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"e781b2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-text e--animation-none\">\n\t\t\t\t<ul id=\"menu-1-e781b2c\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16611\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/campaign-booster-arrow-up\/\" class=\"elementor-item\">Campaign Booster: Arrow Up<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16606\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/campaign-booster-exit-intent-layer\/\" class=\"elementor-item\">Campaign Booster: Exit Intent Layer<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16605\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/campaign-booster-information-bar\/\" class=\"elementor-item\">Campaign Booster: Information Bar<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16610\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/campaign-booster-notification\/\" class=\"elementor-item\">Campaign Booster: Notification<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16604\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/campaign-booster-usp-bar\/\" class=\"elementor-item\">Campaign Booster: USP Bar<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16612\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/add-link-target\/\" class=\"elementor-item\">Add Link Target<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16820\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/browse-mode\/\" class=\"elementor-item\">Browse Mode<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-27017\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/custom-selector\/\" class=\"elementor-item\">Custom Selector Picker<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-17426\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/edit-content\/\" class=\"elementor-item\">Edit Content<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-17421\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/edit-text\/\" class=\"elementor-item\">Edit Text<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-29029\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/move-elements\/\" class=\"elementor-item\">Elemente verschieben<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33902\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/hide-element-2\/\" class=\"elementor-item\">Hide Element<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16600\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/keyword-insertion\/\" class=\"elementor-item\">Keyword Insertion<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-22263\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/redirect-and-split-url-testing\/\" class=\"elementor-item\">Redirect &#038; Split URL Testing<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-15997\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/remove-element\/\" class=\"elementor-item\">Remove Element<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-17423\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/replace-image\/\" class=\"elementor-item\">Replace Image<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-24757\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/responsive-device-switcher\/\" class=\"elementor-item\">Responsive Device Switcher<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16614\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/edit-style\/\" class=\"elementor-item\">Style &#038; Layout \u00c4nderungen<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-e781b2c\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16611\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/campaign-booster-arrow-up\/\" class=\"elementor-item\" tabindex=\"-1\">Campaign Booster: Arrow Up<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16606\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/campaign-booster-exit-intent-layer\/\" class=\"elementor-item\" tabindex=\"-1\">Campaign Booster: Exit Intent Layer<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16605\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/campaign-booster-information-bar\/\" class=\"elementor-item\" tabindex=\"-1\">Campaign Booster: Information Bar<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16610\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/campaign-booster-notification\/\" class=\"elementor-item\" tabindex=\"-1\">Campaign Booster: Notification<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16604\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/campaign-booster-usp-bar\/\" class=\"elementor-item\" tabindex=\"-1\">Campaign Booster: USP Bar<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16612\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/add-link-target\/\" class=\"elementor-item\" tabindex=\"-1\">Add Link Target<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16820\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/browse-mode\/\" class=\"elementor-item\" tabindex=\"-1\">Browse Mode<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-27017\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/custom-selector\/\" class=\"elementor-item\" tabindex=\"-1\">Custom Selector Picker<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-17426\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/edit-content\/\" class=\"elementor-item\" tabindex=\"-1\">Edit Content<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-17421\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/edit-text\/\" class=\"elementor-item\" tabindex=\"-1\">Edit Text<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-29029\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/move-elements\/\" class=\"elementor-item\" tabindex=\"-1\">Elemente verschieben<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33902\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/hide-element-2\/\" class=\"elementor-item\" tabindex=\"-1\">Hide Element<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16600\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/keyword-insertion\/\" class=\"elementor-item\" tabindex=\"-1\">Keyword Insertion<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-22263\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/redirect-and-split-url-testing\/\" class=\"elementor-item\" tabindex=\"-1\">Redirect &#038; Split URL Testing<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-15997\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/remove-element\/\" class=\"elementor-item\" tabindex=\"-1\">Remove Element<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-17423\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/replace-image\/\" class=\"elementor-item\" tabindex=\"-1\">Replace Image<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-24757\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/responsive-device-switcher\/\" class=\"elementor-item\" tabindex=\"-1\">Responsive Device Switcher<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-16614\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/edit-style\/\" class=\"elementor-item\" tabindex=\"-1\">Style &#038; Layout \u00c4nderungen<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1936\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"7\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1936\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Weitere Integrationen <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-1936\" class=\"elementor-element elementor-element-f7b8157 e-con-full e-flex e-con e-child\" data-id=\"f7b8157\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e5ecc6 elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"7e5ecc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-text e--animation-none\">\n\t\t\t\t<ul id=\"menu-1-7e5ecc6\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-38379\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/integrations\/\" class=\"elementor-item\">Integrationen<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-7e5ecc6\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-38379\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/integrations\/\" class=\"elementor-item\" tabindex=\"-1\">Integrationen<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1937\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"8\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1937\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Experten Funktionen <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-1937\" class=\"elementor-element elementor-element-16b7cc0 e-con-full e-flex e-con e-child\" data-id=\"16b7cc0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-84c0e5c elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"84c0e5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-text e--animation-none\">\n\t\t\t\t<ul id=\"menu-1-84c0e5c\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-23799\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/add-css\/\" class=\"elementor-item\">Add CSS<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-28652\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/add-html\/\" class=\"elementor-item\">Add HTML<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-23800\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/add-js\/\" class=\"elementor-item\">Add JavaScript<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-24893\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/add-javascript-reset\/\" class=\"elementor-item\">Add JavaScript Reset<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-45449\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/anti-flicker-script\/\" class=\"elementor-item\">Anti-Flicker-Script<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-23802\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/code-helpers\/\" class=\"elementor-item\">Code Helpers<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-23801\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/edit-html\/\" class=\"elementor-item\">Edit HTML<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-44570\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/experiment-api\/\" class=\"elementor-item\">Experiment API<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-84c0e5c\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-23799\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/add-css\/\" class=\"elementor-item\" tabindex=\"-1\">Add CSS<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-28652\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/add-html\/\" class=\"elementor-item\" tabindex=\"-1\">Add HTML<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-23800\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/add-js\/\" class=\"elementor-item\" tabindex=\"-1\">Add JavaScript<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-24893\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/add-javascript-reset\/\" class=\"elementor-item\" tabindex=\"-1\">Add JavaScript Reset<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-45449\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/anti-flicker-script\/\" class=\"elementor-item\" tabindex=\"-1\">Anti-Flicker-Script<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-23802\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/code-helpers\/\" class=\"elementor-item\" tabindex=\"-1\">Code Helpers<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-23801\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/edit-html\/\" class=\"elementor-item\" tabindex=\"-1\">Edit HTML<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-44570\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/experiment-api\/\" class=\"elementor-item\" tabindex=\"-1\">Experiment API<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1938\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"9\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1938\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Sicherheit <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-1938\" class=\"elementor-element elementor-element-f0ff639 e-con-full e-flex e-con e-child\" data-id=\"f0ff639\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d01e3e elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"0d01e3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-text e--animation-none\">\n\t\t\t\t<ul id=\"menu-1-0d01e3e\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-47645\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/security-features-overview\/\" class=\"elementor-item\">Sicherheitsfunktionen &#8211; \u00dcbersicht aller Features<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-47644\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/role-permission-management\/\" class=\"elementor-item\">Rollen- &amp; Permission Management<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-44688\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/multi-factor-authentication\/\" class=\"elementor-item\">Multi Factor Authentication (MFA)<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-47632\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/session-hijacking-protection\/\" class=\"elementor-item\">Schutz vor Session-Hijacking<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-44691\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/activity-log\/\" class=\"elementor-item\">Activity Log<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-44689\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/active-sessions\/\" class=\"elementor-item\">Active Sessions<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-44690\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/login-history\/\" class=\"elementor-item\">Login History<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-0d01e3e\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-47645\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/security-features-overview\/\" class=\"elementor-item\" tabindex=\"-1\">Sicherheitsfunktionen &#8211; \u00dcbersicht aller Features<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-47644\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/role-permission-management\/\" class=\"elementor-item\" tabindex=\"-1\">Rollen- &amp; Permission Management<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-44688\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/multi-factor-authentication\/\" class=\"elementor-item\" tabindex=\"-1\">Multi Factor Authentication (MFA)<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-47632\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/session-hijacking-protection\/\" class=\"elementor-item\" tabindex=\"-1\">Schutz vor Session-Hijacking<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-44691\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/activity-log\/\" class=\"elementor-item\" tabindex=\"-1\">Activity Log<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-44689\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/active-sessions\/\" class=\"elementor-item\" tabindex=\"-1\">Active Sessions<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-44690\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/login-history\/\" class=\"elementor-item\" tabindex=\"-1\">Login History<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1939\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"10\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1939\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Troubleshooting \/ FAQ <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-1939\" class=\"elementor-element elementor-element-6f00e06 e-con-full e-flex e-con e-child\" data-id=\"6f00e06\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-76affdf elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"76affdf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-text e--animation-none\">\n\t\t\t\t<ul id=\"menu-1-76affdf\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-39607\"><a href=\"https:\/\/varify.io\/de\/userdocumentation\/troubleshooting-faq\/\" class=\"elementor-item\">Troubleshooting (alle)<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-39610\"><a href=\"https:\/\/varify.io\/de\/userdocumentation\/troubleshooting-faq\/?open=tracking\" class=\"elementor-item\">Probleme mit Tracking und Auswertung<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-39608\"><a href=\"https:\/\/varify.io\/de\/userdocumentation\/troubleshooting-faq\/?open=start-and-execution\" class=\"elementor-item\">Probleme mit Experiment Start\/Auslieferung<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-39609\"><a href=\"https:\/\/varify.io\/de\/userdocumentation\/troubleshooting-faq\/?open=editor\" class=\"elementor-item\">Probleme mit dem Editor<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-76affdf\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-39607\"><a href=\"https:\/\/varify.io\/de\/userdocumentation\/troubleshooting-faq\/\" class=\"elementor-item\" tabindex=\"-1\">Troubleshooting (alle)<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-39610\"><a href=\"https:\/\/varify.io\/de\/userdocumentation\/troubleshooting-faq\/?open=tracking\" class=\"elementor-item\" tabindex=\"-1\">Probleme mit Tracking und Auswertung<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-39608\"><a href=\"https:\/\/varify.io\/de\/userdocumentation\/troubleshooting-faq\/?open=start-and-execution\" class=\"elementor-item\" tabindex=\"-1\">Probleme mit Experiment Start\/Auslieferung<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-39609\"><a href=\"https:\/\/varify.io\/de\/userdocumentation\/troubleshooting-faq\/?open=editor\" class=\"elementor-item\" tabindex=\"-1\">Probleme mit dem Editor<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-19310\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"11\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-19310\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Weitere n\u00fctzliche Inhalte <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-19310\" class=\"elementor-element elementor-element-581cfe9 e-con-full e-flex e-con e-child\" data-id=\"581cfe9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-19310\" class=\"elementor-element elementor-element-1ca04d0 e-flex e-con-boxed e-con e-child\" data-id=\"1ca04d0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cbf2145 elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"cbf2145\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;dropdown&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-cbf2145\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-34844\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/create-subscription\/\" class=\"elementor-item\" tabindex=\"-1\">Zahlung &#038; Subscription<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33821\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/agency-account\/\" class=\"elementor-item\" tabindex=\"-1\">Agency Account<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-33930\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/step-by-step-tutorials\/\" class=\"elementor-item\" tabindex=\"-1\">Step-by-Step Tutorials<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-34025\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/multi-factor-authentication\/\" class=\"elementor-item\" tabindex=\"-1\">Multi Factor Authentication (MFA)<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-34846\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Shopify Optimierung<span class=\"sub-arrow\"><i class=\"fas fa-caret-down\" aria-hidden=\"true\"><\/i><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-48469\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/checkout-shopify-app\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Shopify Checkout App<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-38896\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/shopify-tracking\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Shopify Tracking<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-34848\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/shopify-theme-test-with-varify-io\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Shopify Theme testen mit Varify.io<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-40480\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/test-shopify-pdp-templates\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Shopify \u2013 PDP Templates testen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-38712\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/shopify-price-test\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Shopify \u2013 Einrichten eines Preis Tests<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-31795\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/pdp-module-for-shopify-store-2\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Module f\u00fcr Shopify Store kostenlos testen<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-38612\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">WordPress Optimierung<span class=\"sub-arrow\"><i class=\"fas fa-caret-down\" aria-hidden=\"true\"><\/i><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-38897\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/ab-test-hidden-wordpress-content\/\" class=\"elementor-sub-item\" tabindex=\"-1\">WordPress Versteckte Inhalte per Einblendung testen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-38613\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/wordpress-redirect-split-url-testing\/\" class=\"elementor-sub-item\" tabindex=\"-1\">WordPress Redirect &#038; Split URL Testing<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-34845\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">F\u00fcr Nerds<span class=\"sub-arrow\"><i class=\"fas fa-caret-down\" aria-hidden=\"true\"><\/i><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-34847\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/varify-debug\/\" class=\"elementor-sub-item\" tabindex=\"-1\">varify.debug<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-36281\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/varify-success-and-varify-error\/\" class=\"elementor-sub-item\" tabindex=\"-1\">varify_success und varify_error<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-34342\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/cname\/\" class=\"elementor-sub-item\" tabindex=\"-1\">CNAME<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-post menu-item-44569\"><a href=\"https:\/\/varify.io\/es\/userdocumentation\/experiment-api\/\" class=\"elementor-item\" tabindex=\"-1\">Experiment API<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbf03e6 elementor-widget elementor-widget-spacer\" data-id=\"dbf03e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-ee229d0 e-flex e-con-boxed e-con e-parent\" data-id=\"ee229d0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0bba753 elementor-widget elementor-widget-html\" data-id=\"0bba753\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>\n(function () {\n  var SCOPE_SEL =\n    \".elementor-23790 .elementor-element.elementor-element-231dec3 > .elementor-element-populated\";\n  var ACTIVE_SEL = \"a.elementor-item-active\";\n\n  function getScope() {\n    return document.querySelector(SCOPE_SEL);\n  }\n\n  function forceOpenSubmenuForActiveLink(activeLink) {\n    var subMenuUl = activeLink.closest(\"ul.sub-menu\");\n    if (!subMenuUl) return;\n\n    subMenuUl.classList.add(\"is-open\");\n    subMenuUl.setAttribute(\"aria-hidden\", \"false\");\n    subMenuUl.setAttribute(\"aria-expanded\", \"true\");\n\n    var toggle = null;\n    var ulId = subMenuUl.getAttribute(\"id\");\n    if (ulId) toggle = document.querySelector('[aria-controls=\"' + ulId + '\"]');\n\n    if (!toggle) {\n      var parentLi = subMenuUl.closest(\n        \"li.menu-item-has-children, li.page_item_has_children, li.has-children\"\n      );\n      if (parentLi) toggle = parentLi.querySelector(\":scope > a, :scope > button\");\n    }\n    if (toggle) toggle.setAttribute(\"aria-expanded\", \"true\");\n\n    var parentLi2 = subMenuUl.closest(\n      \"li.menu-item-has-children, li.page_item_has_children, li.has-children\"\n    );\n    if (parentLi2) parentLi2.classList.add(\"open\", \"is-open\");\n\n    var container = subMenuUl.closest(\n      \".elementor-nav-menu__container, .elementor-nav-menu--dropdown\"\n    );\n    if (container) {\n      container.classList.add(\"is-open\");\n      container.setAttribute(\"aria-hidden\", \"false\");\n    }\n  }\n\n  function openParentsForLink(link) {\n    var el = link;\n    while (el && el !== document.body) {\n      if (el.tagName === \"DETAILS\") el.open = true;\n\n      if (el.tagName === \"UL\" && el.classList && el.classList.contains(\"sub-menu\")) {\n        el.classList.add(\"is-open\");\n        el.setAttribute(\"aria-hidden\", \"false\");\n        el.setAttribute(\"aria-expanded\", \"true\");\n\n        var ulId = el.getAttribute(\"id\");\n        if (ulId) {\n          var controller = document.querySelector('[aria-controls=\"' + ulId + '\"]');\n          if (controller) controller.setAttribute(\"aria-expanded\", \"true\");\n        }\n      }\n\n      var directToggle =\n        el.querySelector(\":scope > button[aria-expanded], :scope > a[aria-expanded]\") || null;\n      if (directToggle) directToggle.setAttribute(\"aria-expanded\", \"true\");\n\n      if (el.classList) {\n        if (el.matches(\"li.menu-item-has-children\")) el.classList.add(\"open\");\n        if (el.matches(\"li.menu-item-has-children, li.page_item_has_children, li.has-children\"))\n          el.classList.add(\"is-open\");\n        if (el.matches(\".elementor-item, .elementor-nav-menu-item\"))\n          el.classList.add(\"is-active-path\");\n        if (el.matches(\".elementor-nav-menu__container, .elementor-nav-menu--dropdown\")) {\n          el.classList.add(\"is-open\");\n          el.setAttribute(\"aria-hidden\", \"false\");\n        }\n      }\n      el = el.parentElement;\n    }\n  }\n\n  function applyOnce() {\n    var scope = getScope();\n    if (!scope) return;\n\n    var actives = scope.querySelectorAll(ACTIVE_SEL);\n    if (!actives || actives.length === 0) return;\n\n    Array.prototype.slice.call(actives).forEach(function (a) {\n      a.setAttribute(\"aria-current\", \"page\");\n      forceOpenSubmenuForActiveLink(a);\n      openParentsForLink(a);\n    });\n  }\n\n  function closeNonActiveBranches() {\n    var scope = getScope();\n    if (!scope) return;\n\n    var active = scope.querySelector(ACTIVE_SEL);\n\n    var openItems = scope.querySelectorAll(\n      \"li.menu-item-has-children.open, li.menu-item-has-children.is-open, \" +\n      \"li.page_item_has_children.is-open, li.has-children.is-open\"\n    );\n\n    Array.prototype.slice.call(openItems).forEach(function (li) {\n      if (active && li.contains(active)) return;\n\n      li.classList.remove(\"open\", \"is-open\");\n\n      var t = li.querySelector(\":scope > a[aria-expanded], :scope > button[aria-expanded]\");\n      if (t) t.setAttribute(\"aria-expanded\", \"false\");\n\n      var ul = li.querySelector(\":scope > ul.sub-menu\");\n      if (ul) {\n        ul.classList.remove(\"is-open\");\n        ul.setAttribute(\"aria-hidden\", \"true\");\n        ul.setAttribute(\"aria-expanded\", \"false\");\n      }\n    });\n\n    Array.prototype.slice.call(scope.querySelectorAll(\"details[open]\")).forEach(function (d) {\n      if (active && d.contains(active)) return;\n      d.open = false;\n    });\n  }\n\n  function enhanceAccordionBehavior() {\n    var scope = getScope();\n    if (!scope) return;\n    if (scope.dataset.varifyMenuEnhanced === \"1\") return;\n    scope.dataset.varifyMenuEnhanced = \"1\";\n\n    scope.addEventListener(\"pointerdown\", function (e) {\n      var toggle = e.target.closest(\n        \"a.has-submenu, a[aria-haspopup='true'], button[aria-haspopup='true']\"\n      );\n      if (!toggle || !scope.contains(toggle)) return;\n\n      var li = toggle.closest(\n        \"li.menu-item-has-children, li.page_item_has_children, li.has-children\"\n      );\n      if (!li) return;\n\n      Array.prototype.slice\n        .call(\n          scope.querySelectorAll(\n            \"li.menu-item-has-children.open, li.menu-item-has-children.is-open\"\n          )\n        )\n        .forEach(function (other) {\n          if (other === li || other.contains(li)) return;\n          other.classList.remove(\"open\", \"is-open\");\n\n          var t = other.querySelector(\n            \":scope > a[aria-expanded], :scope > button[aria-expanded]\"\n          );\n          if (t) t.setAttribute(\"aria-expanded\", \"false\");\n\n          var ul = other.querySelector(\":scope > ul.sub-menu\");\n          if (ul) {\n            ul.classList.remove(\"is-open\");\n            ul.setAttribute(\"aria-hidden\", \"true\");\n            ul.setAttribute(\"aria-expanded\", \"false\");\n          }\n        });\n    });\n  }\n\n  function init() {\n    applyOnce();\n    closeNonActiveBranches();\n\n    setTimeout(function () { applyOnce(); closeNonActiveBranches(); }, 150);\n    setTimeout(function () { applyOnce(); closeNonActiveBranches(); }, 600);\n    setTimeout(function () { applyOnce(); closeNonActiveBranches(); }, 1200);\n\n    enhanceAccordionBehavior();\n  }\n\n  if (document.readyState === \"loading\") {\n    document.addEventListener(\"DOMContentLoaded\", init);\n  } else {\n    init();\n  }\n})();\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/li>\n<li id=\"custom_html-2\" class=\"widget_text widget widget_custom_html\"><div class=\"textwidget custom-html-widget\"><script>\r\n\/\/ Function to check the URL hash and scroll to the element\r\nfunction checkAndScrollToHash() {\r\n    const urlHash = window.location.hash; \/\/ Get the current URL hash\r\n    if (urlHash) {\r\n        const targetElement = document.querySelector(urlHash); \/\/ Try to find the element matching the hash\r\n        if (targetElement) {\r\n            \/\/ Scroll to the element using scrollIntoView\r\n            targetElement.scrollIntoView({\r\n                behavior: 'smooth',\r\n                block: 'start'\r\n            });\r\n        }\r\n    }\r\n}\r\n\r\n\/\/ Execute the function once, one second after the page loads\r\nsetTimeout(checkAndScrollToHash, 1000);\r\n<\/script>\r\n<\/div><\/li>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Manuelle Google Tag Manager Tracking-Integration Diese Anleitung gilt f\u00fcr Accounts, die ihr Tracking nicht bis zum 11.02.2025 eingerichtet haben. Falls dein Account bereits ein Tracking-Setup besitzt, bleibt alles wie gewohnt bestehen \u2013 es sind keine \u00c4nderungen erforderlich. M\u00f6chtest du dennoch auf das neue Tracking Setup umsteigen? Hier erf\u00e4hrst du, wie das geht: Migration zum Tracking [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[21,38],"tags":[],"class_list":["post-18876","post","type-post","status-publish","format-standard","hentry","category-userdocumentation","category-web-analytics-integrations"],"_links":{"self":[{"href":"https:\/\/varify.io\/es\/wp-json\/wp\/v2\/posts\/18876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/varify.io\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/varify.io\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/varify.io\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/varify.io\/es\/wp-json\/wp\/v2\/comments?post=18876"}],"version-history":[{"count":310,"href":"https:\/\/varify.io\/es\/wp-json\/wp\/v2\/posts\/18876\/revisions"}],"predecessor-version":[{"id":48554,"href":"https:\/\/varify.io\/es\/wp-json\/wp\/v2\/posts\/18876\/revisions\/48554"}],"wp:attachment":[{"href":"https:\/\/varify.io\/es\/wp-json\/wp\/v2\/media?parent=18876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/varify.io\/es\/wp-json\/wp\/v2\/categories?post=18876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/varify.io\/es\/wp-json\/wp\/v2\/tags?post=18876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}